{"id":260528,"date":"2025-06-02T17:02:53","date_gmt":"2025-06-02T15:02:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=260528"},"modified":"2025-06-02T17:08:37","modified_gmt":"2025-06-02T15:08:37","slug":"paura-per-due-incidenti-sulla-ss-280-sei-auto-coinvolte-otto-persone-ferite-tra-cui-un-bambino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/paura-per-due-incidenti-sulla-ss-280-sei-auto-coinvolte-otto-persone-ferite-tra-cui-un-bambino\/","title":{"rendered":"Paura per due incidenti sulla SS 280: sei auto coinvolte. Otto persone ferite tra cui un bambino"},"content":{"rendered":"<p>CATANZARO &#8211; Doppio intervento da parte dei vigili del fuoco per <strong>due distinti incidenti avvenuti nel giro di 30 minuti<\/strong>, tutti lungo la Statale 280 e non distanti l&#8217;uno dall&#8217;altro. Il bilancio \u00e8 di <strong>otto persone ferite tutte trasportate in ospedale<\/strong> compreso un bambino. Nel primo pomeriggio di oggi, alle ore 15:30 circa, una squadra dei Vigili del Fuoco del Comando provinciale di Catanzaro \u00e8 intervenuta per il<strong> primo incidente stradale avvenuto sulla Strada Statale 280, in direzione Catanzaro, nei pressi dello svincolo per il Comune di Settingiano<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-260531 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_1.jpg\" alt=\"Incidente Statale 280_1\" width=\"534\" height=\"371\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_1.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_1-300x209.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_1-768x534.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_1-604x420.jpg 604w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_1-150x104.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_1-218x150.jpg 218w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_1-696x484.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_1-100x70.jpg 100w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/p>\n<p>Nell\u2019impatto sono<strong> rimaste coinvolte due autovetture<\/strong>. <strong>Sei le persone ferite, tra cui un bambino e una persona rimasta incastrata all\u2019interno<\/strong> dell\u2019abitacolo sul lato conducente. Quest\u2019ultima \u00e8 stata estratta grazie all&#8217;intervento del personale dei vigili del fuoco e successivamente affidata alle cure del personale sanitario del 118. <strong>Tutti i feriti sono stati trasportati presso le strutture ospedaliere di Catanzaro.<\/strong><\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-260528 gallery-columns-2 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/quicosenza.it\/news\/paura-per-due-incidenti-sulla-ss-280-sei-auto-coinvolte-otto-persone-ferite-tra-cui-un-bambino\/incidente-statale-280_2\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"206\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_2-300x206.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_2-300x206.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_2-768x527.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_2-612x420.jpg 612w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_2-150x103.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_2-218x150.jpg 218w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_2-696x478.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_2-100x70.jpg 100w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_2.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/quicosenza.it\/news\/paura-per-due-incidenti-sulla-ss-280-sei-auto-coinvolte-otto-persone-ferite-tra-cui-un-bambino\/incidente-statale-280_3-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"208\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_3-2-300x208.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_3-2-300x208.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_3-2-768x533.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_3-2-605x420.jpg 605w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_3-2-150x104.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_3-2-218x150.jpg 218w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_3-2-696x483.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_3-2-100x70.jpg 100w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/Incidente-Statale-280_3-2.jpg 970w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Successivamente, alle ore 16:00 circa, la stessa squadra \u00e8 stata tempestivamente dirottata su <strong>u<\/strong>n<strong> secondo incidente avvenuto a poca distanza dal primo,<\/strong> sempre lungo la Statale 280.<strong> In questo secondo sinistro sono rimaste coinvolte quattro autovetture<\/strong>.\u00a0<strong>Come detto il bilancio complessivo dei due incidenti \u00e8 di otto persone ferite, trasportate in ospedale tra Catanzaro e Lamezia Terme<\/strong>. Sul posto sono intervenuti anche i sanitari del 118, la Polizia Stradale per i rilievi del caso, e personale ANAS per la gestione del traffico. Al momento \u00e8 segnalata<strong> la chiusura temporanea di una corsia<\/strong> al fine di consentire le operazioni di soccorso e messa in sicurezza delle vetture coinvolte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Doppio intervento da parte dei vigili del fuoco per due distinti incidenti avvenuti nel giro di 30 minuti, tutti lungo la Statale 280 e non distanti l&#8217;uno dall&#8217;altro. Il bilancio \u00e8 di otto persone ferite tutte trasportate in ospedale compreso un bambino. Nel primo pomeriggio di oggi, alle ore 15:30 circa, una squadra [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":260529,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-260528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/260528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=260528"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/260528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/260529"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=260528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=260528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=260528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}