{"id":260819,"date":"2025-06-08T09:59:57","date_gmt":"2025-06-08T07:59:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=260819"},"modified":"2025-06-08T10:00:27","modified_gmt":"2025-06-08T08:00:27","slug":"parchi-acquatici-a-rende-e-cosenza-milioni-di-euro-per-il-mare-in-citta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/parchi-acquatici-a-rende-e-cosenza-milioni-di-euro-per-il-mare-in-citta\/","title":{"rendered":"Parchi acquatici a Rende e Cosenza, milioni di euro per il \u201cmare in citt\u00e0\u201d"},"content":{"rendered":"<p>COSENZA \u2013 Il \u201cmare in citt\u00e0\u201d, un sogno per cosentini e rendesi. Un\u2019ambizione in parte diventata realt\u00e0 a Rende con il <a href=\"https:\/\/www.parcosantachiara.it\/\" rel=\"noopener\">Parco acquatico di Santa Chiara<\/a>, ma abbandonata tra le sterpaglie del Parco acquatico del Crati a Cosenza. Le due infrastrutture <strong>sono costate ai cittadini almeno 30 milioni di euro<\/strong>. Nel Principato la gara per aggiudicarne la gestione \u00e8 andata deserta (per la seconda volta), mentre pesano come un macigno le dichiarazioni della commissione d\u2019accesso antimafia sull\u2019attuale affidatario. Su LungoCrati invece i lavori sono fermi da oltre 10 anni, il manufatto con le vasche costruito \u00e8 stato svaligiato a pi\u00f9 riprese (nulla resta ormai di condizionatori o sanitari) e l\u2019amministrazione Caruso non sembrerebbe manifestare alcun interesse per le piscine inutilizzate.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-191589 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/parcoacquatico801.jpg\" alt=\"\" width=\"523\" height=\"324\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/parcoacquatico801.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/parcoacquatico801-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/parcoacquatico801-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/parcoacquatico801-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/parcoacquatico801-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/parcoacquatico801-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/02\/parcoacquatico801-356x220.jpg 356w\" sizes=\"auto, (max-width: 523px) 100vw, 523px\" \/><\/p>\n<h4><strong>Parco acquatico Santa Chiara<\/strong><\/h4>\n<p>Nessuno ha inteso partecipare al bando per aggiudicarsi la gestione del Parco Acquatico Santa Chiara. Il valore della <strong>gara scaduta il 9 maggio 2025 \u00e8 di 16 milioni e 709mila euro<\/strong> (di presunti incassi in 20 anni), mentre in quella andata deserta il 3 marzo 2025 l\u2019importo totale dell\u2019appalto era pi\u00f9 alto: 19 milioni e 276mila euro. Un vero e proprio fallimento per i commissari chiamati a prorogare di 6 mesi la permanenza al Comune di Rende sciolto per infiltrazioni mafiose, proprio per affidare a nuovo gestore il parco acquatico e \u00abscongiurare il paventato pericolo che possano determinarsi circostanze atte a favorire il ritorno di soggetti vicini ad ambienti criminali\u00bb.<\/p>\n<p>Intanto in assenza di offerte pervenute, la disponibilit\u00e0 sembrerebbe restare in carico alla <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/rende\/parco-acquatico-ecco-chi-gestisce-il-gioiello-di-rende-esempio-di-malaffare\">Marconi Village srl<\/a> citata nella relazione d\u2019accesso antimafia come \u00abun altro esempio di non corretta gestione del patrimonio immobiliare che ha consentito a soggetti con pregiudizi di polizia di ottenere indebiti arricchimenti a scapito della collettivit\u00e0\u00bb. Il riferimento \u00e8 ad Antonio Fusinato, 40enne compagno della messicana Maria Candelaria De Rose che risulta amministratrice unica della societ\u00e0. Il business continua quindi a fruttare sia d\u2019estate (con lettini noleggiati a 13\/15 euro al giorno) sia d\u2019inverno (tra il 2021 e il 2022 circa 1 milione e mezzo di euro incassati per ospitare concorsi pubblici). Eppure nessuno vuole prendersene carico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-260822 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parco-acquatico-crati-cosenza.jpg\" alt=\"\" width=\"486\" height=\"301\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parco-acquatico-crati-cosenza.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parco-acquatico-crati-cosenza-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parco-acquatico-crati-cosenza-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parco-acquatico-crati-cosenza-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parco-acquatico-crati-cosenza-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parco-acquatico-crati-cosenza-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parco-acquatico-crati-cosenza-356x220.jpg 356w\" sizes=\"auto, (max-width: 486px) 100vw, 486px\" \/><\/p>\n<h4><strong>Parco acquatico del Crati<\/strong><\/h4>\n<p><strong>\u00a0<\/strong>I <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/cosenza\/130716-progetto-parco-acquatico-due-anni-per-constatare-il-blocco-dei-lavori-altri-10-per-finirlo\">lavori del Parco acquatico del Crati<\/a> sono invece partiti nel 2008 e dovevano essere terminati nel 2010. Si sono arenati ufficialmente nel 2016, nonostante l\u2019allora sindaco Mario Occhiuto avesse promesso di tagliare il nastro entro marzo 2015. <strong>La piscina coperta semi-olimpionica (destinata ad allenamenti e riabilitazione<\/strong>) e le <strong>due piscine scoperte<\/strong> (una per i bimbi e una per gli adulti lunga 25 metri), <strong>mai entrate in funzione<\/strong>, sono costate ai cosentini oltre <strong>2 milioni e mezzo di euro<\/strong> su un finanziamento iniziale di 3 milioni e mezzo di euro. Soldi a cui si sommano le cifre gi\u00e0 destinate al progetto (altri 500mila euro); 1 milione di euro per il completamento dell\u2019opera avviato nel 2014, nonch\u00e9 dell\u2019edificio di supporto all\u2019impianto (che avrebbe dovuto ospitare la biglietteria, gli spogliatoi, le docce, gli uffici); 200mila euro per il fotovoltaico; 50mila euro per gli allacci alla rete idrica, fognaria, gas; nonch\u00e9 ingenti fondi per riacquistare il materiale rubato negli anni dal cantiere incustodito.<\/p>\n<p>L\u2019infrastruttura circondata ormai dalla vegetazione si trova al confine tra il <strong>Comune di Cosenza e Casali del Manco,<\/strong> al termine di via Bendicenti nella frazione di Sant\u2019Ippolito. Un\u2019opera inserita in una pi\u00f9 ampia iniziativa di riqualificazione fluviale con l\u2019obiettivo di allestire aree attrezzate lungo le sponde del Crati che sarebbe stato reso navigabile alle piccole imbarcazioni. Il blocco definitivo dei lavori, oggetto delle attenzioni della Guardia di Finanza interessata a ricostruire la spendita dei fondi pubblici, \u00e8 stato sancito dalla rescissione del contratto della ditta aggiudicataria dell\u2019appalto. Una triste vicenda di denaro speso dalla collettivit\u00e0, senza ottenere in cambio alcun tipo di servizio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-260820 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parchi-acquatici-cosenza-rende-02.jpg\" alt=\"\" width=\"561\" height=\"316\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parchi-acquatici-cosenza-rende-02.jpg 800w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parchi-acquatici-cosenza-rende-02-300x169.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parchi-acquatici-cosenza-rende-02-768x432.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parchi-acquatici-cosenza-rende-02-747x420.jpg 747w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parchi-acquatici-cosenza-rende-02-150x84.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/06\/parchi-acquatici-cosenza-rende-02-696x392.jpg 696w\" sizes=\"auto, (max-width: 561px) 100vw, 561px\" \/><\/p>\n<h4><strong>Il flop dei parchi acquatici di Rende e Cosenza<\/strong><\/h4>\n<p>I parchi acquatici di Rende e Cosenza attualmente pare non siano appetibili. <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/parco-acquatico-a-rende-deserta-la-gara-per-il-mare-in-citta\">Nessun privato ad oggi sembrerebbe essere interessato<\/a> ufficialmente a investire per gestirli in prima persona. <strong>Le ragioni sarebbero da ricondurre agli alti costi per le utenze.<\/strong> Un problema che a Rende il nuovo gestore dovr\u00e0 risolvere spendendo 2 milioni di euro per rendere l\u2019impianto meno energivoro (e ridurre le spese), godendo allo stesso tempo dei nuovi spazi di sosta finanziati dal Comune con 2.850.000 euro.<\/p>\n<p>Non c\u2019\u00e8 per\u00f2 da stupirsi se il mondo delle imprese snobba il Parco Santa Chiara, perch\u00e9 il bando andato deserto per due volte, pur essendo sbandierato dalla <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/rende-commissariata-gli-ultimi-atti-firmati-tra-assunzioni-e-tasse-ridotte\">terna commissariale come un obiettivo raggiunto<\/a>, \u00e8 identico a quello stilato durante la Giunta Manna prima dello scioglimento per infiltrazioni mafiose. Il risultato era quindi scontato. Il Parco acquatico del Crati dal suo canto, stenta a decollare anche se l\u201987% dei pagamenti \u00e8 gi\u00e0 stato incassato dal Comune di Cosenza. La sua esistenza \u00e8 ignorata, fuori dall\u2019agenda politica attuale di Palazzo dei Bruzi. Nonostante avrebbe potuto realmente contribuire a ripopolare l\u2019area restituendo dignit\u00e0 al lungofiume boulevard e ai suoi sempre pi\u00f9 dimenticati BoCs Art. Una sfida, per ora, persa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 Il \u201cmare in citt\u00e0\u201d, un sogno per cosentini e rendesi. Un\u2019ambizione in parte diventata realt\u00e0 a Rende con il Parco acquatico di Santa Chiara, ma abbandonata tra le sterpaglie del Parco acquatico del Crati a Cosenza. Le due infrastrutture sono costate ai cittadini almeno 30 milioni di euro. Nel Principato la gara per [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":260821,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-260819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/260819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=260819"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/260819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/260821"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=260819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=260819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=260819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}