{"id":260854,"date":"2025-06-06T15:52:07","date_gmt":"2025-06-06T13:52:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=260854"},"modified":"2025-06-06T15:52:58","modified_gmt":"2025-06-06T13:52:58","slug":"ex-llu-lpu-contributi-mai-versati-confial-apre-la-vertenza-e-avvia-le-assemblee-da-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ex-llu-lpu-contributi-mai-versati-confial-apre-la-vertenza-e-avvia-le-assemblee-da-cosenza\/","title":{"rendered":"Ex Llu-Lpu, contributi mai versati: Confial apre la vertenza e avvia le assemblee da Cosenza"},"content":{"rendered":"<p>COSENZA \u2013 Nella sede SNALV di Piazza dei Bruzi n.5 a Cosenza, la CONFIAL d\u00e0 il via luned\u00ec 9 giugno alle 17, ad un ciclo di <strong>assemblee territoriali per affrontare una delle questioni pi\u00f9 spinose che riguardano gli ex LSU-LPU<\/strong> (Lavoratori Socialmente Utili e di Pubblica Utilit\u00e0): quella dei contributi previdenziali non versati.<\/p>\n<p>Il sindacato, guidato a livello regionale da Roberto Castagna, punta a costruire una mobilitazione forte e strutturata per ottenere giustizia su una vicenda che, se non sanata, rischia di compromettere le pensioni di centinaia di lavoratori precari, oggi in servizio presso Comuni ed enti locali. <strong>\u201cMolti sono prossimi alla pensione<\/strong>, ma \u2013 spiega Castagna \u2013 senza il riconoscimento dei contributi, percepiranno assegni irrisori. <strong>\u00c8 una vera e propria ingiustizia sociale\u201d.<\/strong><\/p>\n<p>La Confial richiama l\u2019attenzione <strong>sull\u2019urgenza di dare seguito al disegno di legge parlamentare n. 539<\/strong>, che prevede la regolarizzazione previdenziale dei periodi di lavoro precario svolti da LSU-LPU, spesso per anni e senza tutele adeguate.\u00a0Intanto, \u00e8 considerata positiva la <strong>mozione presentata dal gruppo PD in Consiglio regionale<\/strong>, che impegna la Giunta calabrese a sostenere una proposta unitaria da portare alla Conferenza Stato-Regioni. Ma per il sindacato \u201ci tempi sono maturi\u201d e servono atti concreti.\u00a0La campagna di assemblee promossa da Confial partir\u00e0 dal cosentino per poi estendersi su tutto il territorio regionale. L\u2019obiettivo \u00e8 chiaro: far sentire la voce dei lavoratori e spingere istituzioni e Parlamento a colmare un vuoto che penalizza migliaia di persone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 Nella sede SNALV di Piazza dei Bruzi n.5 a Cosenza, la CONFIAL d\u00e0 il via luned\u00ec 9 giugno alle 17, ad un ciclo di assemblee territoriali per affrontare una delle questioni pi\u00f9 spinose che riguardano gli ex LSU-LPU (Lavoratori Socialmente Utili e di Pubblica Utilit\u00e0): quella dei contributi previdenziali non versati. Il sindacato, [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":141952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-260854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/260854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=260854"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/260854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/141952"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=260854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=260854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=260854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}