{"id":261161,"date":"2025-06-10T11:27:34","date_gmt":"2025-06-10T09:27:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=261161"},"modified":"2025-06-10T12:09:11","modified_gmt":"2025-06-10T10:09:11","slug":"marano-marchesato-si-dimette-il-consiglio-comunale-lex-sindaco-vivacqua-rompe-il-silenzio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/marano-marchesato-si-dimette-il-consiglio-comunale-lex-sindaco-vivacqua-rompe-il-silenzio\/","title":{"rendered":"Marano Marchesato, si dimette il Consiglio Comunale: l&#8217;ex sindaco Vivacqua rompe il silenzio"},"content":{"rendered":"<p>MARANO MARCHESATO (CS) \u2013 &#8220;In data 7 giugno, con un gesto che ha colto di sorpresa l\u2019intera cittadinanza, quattro consiglieri di minoranza e tre di maggioranza hanno rassegnato contemporaneamente le proprie dimissioni, determinando cos\u00ec lo <a href=\"https:\/\/quicosenza.it\/news\/provincia\/marano-marchesato-sciolto-il-consiglio-comunale-nominato-un-commissario-prefettizio\">scioglimento del Consiglio Comunale di Marano Marchesato<\/a>&#8220;. A intervenire pubblicamente sulla vicenda \u00e8 l\u2019ormai ex sindaco <strong>Eduardo Vivacqua<\/strong>, che esprime il suo <strong>rammarico<\/strong> e la sua <strong>interpretazione dei fatti<\/strong>, ancora oggi poco chiari e privi \u2013 a suo dire \u2013 di motivazioni oggettive.<\/p>\n<h4>Vivacqua: \u201cUn atto immotivato e irresponsabile\u201d<\/h4>\n<p>&#8220;Solo a distanza di tre giorni, i <strong>tre consiglieri di maggioranza dimissionari<\/strong> hanno comunicato che la loro scelta \u00e8 stata dettata da una presunta <strong>&#8216;necessit\u00e0 di cambio di rotta amministrativa<\/strong>&#8216;, rimasta, secondo loro, inascoltata. Una spiegazione che Vivacqua contesta con fermezza. Ogni scelta amministrativa \u00e8 sempre stata condivisa con l\u2019intero gruppo \u2013 scrive Vivacqua \u2013 con l\u2019approvazione di ogni singolo membro. Mai \u00e8 emersa alcuna divergenza che facesse pensare a una rottura imminente&#8221;.<\/p>\n<h4>L\u2019affondo ai consiglieri dimissionari<\/h4>\n<p>L\u2019ex primo cittadino si sofferma in particolare su tre nomi: <strong>Giampietro Napparo, Agostino Napoli e Ida Guido:<\/strong> &#8220;restiamo di stucco perch\u00e9 nei due anni di amministrazione ogni scelta che c\u2019era da prendere \u00e8 stata sempre discussa con l\u2019intero gruppo e soprattuto con l\u2019approvazione di ogni singolo membro e mi pare senza che nessuno mai manifestasse ragioni e motivazioni di contrasto con la politica dell\u2019amministrazione al di l\u00e0 di un normale confronto che quotidianamente tutti gli amministratori sono chiamati a svolgere, non che questo sia avvenuto da parte di tutti. In particolare mi riferisco al consigliere Giampiero Napparo che \u00e8 stata un\u2019assenza costante sin dal momento dell\u2019insediamento del Consiglio Comunale sia nella quotidianit\u00e0 amministrativa che nei giorni di riunione di maggioranza&#8221;.<\/p>\n<p>&#8220;Per quanto riguarda i <strong>consiglieri Napoli e Guido,<\/strong> nonch\u00e9 rispettivamente Vicesindaco e Assessore di questa amministrazione, non ho mai riscontrato che non condividessero le decisioni prese avendo sempre votato favorevolmente a tutti i consigli fatti fin ora approvando bilancio preventivo, rendiconto 2024 e anche il PSC, un grande passo in avanti importantissimo per la nostra comunit\u00e0 perseguito in maniera incessante dalla nostra amministrazione. In particolare, il <strong>rammarico pi\u00f9 grande, \u00e8 per il vicesindaco Napoli<\/strong> che ha avuto sin <strong>da subito carta bianca su tutto<\/strong>. Membro della giunta e mia persona di fiducia, avendo operato con me anche nella precedente amministrazione e scegliendo di ricandidarsi al mio fianco, ha sempre gestito e organizzato lui personalmente il lavoro sulla manutenzione e pulizia stradale senza che nessuno interferisse con il suo operato e sulle sue scelte, attivit\u00e0 adesso criticata dagli stessi che lo sostengono dando la colpa all\u2019amministrazione da me gestita. <strong>Fino all\u2019ultimo momento<\/strong> &#8211; prosegue Vivacqua &#8211; ha <strong>messo in atto un doppio gioco<\/strong> dove il giorno prima di dimettersi programmava con me atti per il futuro mentre aveva gi\u00e0 in piano di girarmi le spalle di punto in bianco senza una motivazione plausibile. Mi viene difficile, dunque, credere al comunicato fatto dagli stessi, le dimissioni sono del tutto immotivate e a disposizione di chiunque. A chi mi chiede come mai sia finita la mia amministrazione non posso dare una risposta fondata su elementi oggettivi; non sussistono&#8221;.<\/p>\n<h4>\u201cUna pugnalata alla cittadinanza\u201d<\/h4>\n<p>&#8220;Si tratta di un atto di vigliaccheria nei confronti dei cittadini che hanno perso un punto di riferimento nella comunit\u00e0 perch\u00e9 \u00e8 un comportamento irriguardoso innanzitutto nei confronti del ruolo svolto e del mandato ricevuto dagli elettori. La vera motivazione temo che non la sapremo mai, possiamo solo immaginare e mi vien da pensare che si tratti di un atto mosso contro me a livello personale a discapito del nostro Paese. La caduta di una amministrazione e la nomina di un <strong>Commissario Prefettizio, che svolger\u00e0 solo atti di ordinaria amministrazione<\/strong>, sono il risultato di un gesto ignorante e irresponsabile di chi oggi non pu\u00f2 certo dire di amare il Paese! Certo che il tempo rimetter\u00e0 ogni cosa al suo posto, insieme alla maggioranza fattiva della mia amministrazione restiamo a disposizione per la nostra comunit\u00e0!&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MARANO MARCHESATO (CS) \u2013 &#8220;In data 7 giugno, con un gesto che ha colto di sorpresa l\u2019intera cittadinanza, quattro consiglieri di minoranza e tre di maggioranza hanno rassegnato contemporaneamente le proprie dimissioni, determinando cos\u00ec lo scioglimento del Consiglio Comunale di Marano Marchesato&#8220;. A intervenire pubblicamente sulla vicenda \u00e8 l\u2019ormai ex sindaco Eduardo Vivacqua, che esprime [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":148512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-261161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/261161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=261161"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/261161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/148512"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=261161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=261161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=261161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}