{"id":26171,"date":"2013-09-24T11:56:15","date_gmt":"2013-09-24T09:56:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26171"},"modified":"2023-01-17T13:23:41","modified_gmt":"2023-01-17T12:23:41","slug":"10722-protesta-sotto-la-curia-di-cosenza-ridateci-il-vecchio-parroco","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/10722-protesta-sotto-la-curia-di-cosenza-ridateci-il-vecchio-parroco\/","title":{"rendered":"Protesta sotto la Curia di Cosenza: &#8220;Ridateci il vecchio parroco&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; Il Vescovo rimuove il prelato dalla propria diocesi, i fedeli insorgono.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Diverse decine di abitanti di Fiumefreddo Bruzio hanno tenuto stamane un sit-in di protesta davanti alla sede della Curia di Cosenza. La contestazione \u00e8 motivata dal fatto che l&#8217;arcivescovo di Cosenza, monsignor Salvatore Nunnari, ha annunciato il trasferimento del parroco del centro del tirreno cosentino, Don Mauro Francesco Fratucci. Ma la popolazione non \u00e8 d&#8217;accordo. Una delegazione di 8 persone ha incontrato il vicario della Curia, che per\u00f2 non ha saputo dare spiegazioni precise in merito al trasferimento. Si attendono adesso notizie dal vescovo. Intanto per domani sera, alle ore 20,30, e&#8217; stata organizzata una fiaccolata silenziosa per le vie di Fiumefreddo Bruzio, per sensibilizzare l&#8217;opinione pubblica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il Vescovo rimuove il prelato dalla propria diocesi, i fedeli insorgono.<\/p>\n","protected":false},"author":22,"featured_media":26172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-26171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26171"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26172"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}