{"id":262340,"date":"2025-06-24T13:30:41","date_gmt":"2025-06-24T11:30:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=262340"},"modified":"2025-06-24T13:06:02","modified_gmt":"2025-06-24T11:06:02","slug":"maltrattamenti-e-abusi-approvate-le-linee-di-indirizzo-per-il-sistema-di-tutela-e-prevenzione-dei-bambini","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/maltrattamenti-e-abusi-approvate-le-linee-di-indirizzo-per-il-sistema-di-tutela-e-prevenzione-dei-bambini\/","title":{"rendered":"Maltrattamenti e abusi: approvate le Linee di indirizzo per il sistema di tutela e prevenzione dei bambini"},"content":{"rendered":"<p>CATANZARO &#8211; In Calabria si punta a <strong>contrastare la povert\u00e0 educativa<\/strong> legata all&#8217;infanzia, come mai fatto prima d&#8217;ora, con<strong> l&#8217;approvazione delle linee d&#8217;indirizzo per il sistema di tutela e prevenzione dei bambini.<\/strong> Un documento strategico che punta a rafforzare i servizi rivolti alla prima infanzia contrastando il rischio di maltrattamenti, abusi e condotte inappropriate nei servizi educativi e di istruzione.<\/p>\n<p>L&#8217;obiettivo \u00e8 quello di offrire un&#8217;offerta educativa di qualit\u00e0 a tutti i bambini e le bambine della regione puntando a colmare il gap che c&#8217;\u00e8 con le altre regioni d&#8217;Italia e con il resto dei Paesi europei.<em>\u00a0&#8220;Con queste linee guida<\/em> \u2013 dichiara l&#8217;assessore all&#8217;Istruzione della Regione Calabria, <strong>Maria Stefania Caracciolo<\/strong> \u2013 <em>proseguiamo nel percorso intrapreso, finalizzato non solo ad implementare i servizi educativi e di istruzione ma soprattutto a qualificarli perch\u00e9 la <strong>qualit\u00e0 dell&#8217;educazione<\/strong> passa anche e soprattutto dalla capacit\u00e0 di <strong>proteggere e promuovere ambienti sicuri, trasparenti e rispettosi;<\/strong> esse rappresentano un atto concreto di responsabilit\u00e0 verso i nostri bambini, le famiglie e gli operatori del settore&#8221;.<\/em><\/p>\n<h3>Tutela e prevenzione dei bambini: cosa prevedono le Linee guida in Calabria<\/h3>\n<p>Le linee di indirizzo per il sistema di prevenzione e tutela dei bambini sono state istituite nel corso di un percorso nel quale oltre alla Regione hanno collaborato anche\u00a0Anci, Usr e le associazioni rappresentative dell&#8217;infanzia. Tra le novit\u00e0 inserite l&#8217;adozione di un <strong>Codice di condotta<\/strong> a cura dei soggetti gestori, con norme comportamentali per il personale e modalit\u00e0 di segnalazione efficaci.<\/p>\n<p>Si prevede anche un<strong> piano di prevenzione e tutela<\/strong> incentrato su formazione, coordinamento pedagogico, collegialit\u00e0, valutazione della qualit\u00e0 e partecipazione delle famiglie. Si punta inoltre ad un <strong>uso consapevole delle tecnologie digitali<\/strong>, con particolare attenzione all&#8217;impatto degli smartphone sui bambini pi\u00f9 piccoli e a inserire\u00a0<strong>misure per contrastare lo stress sul lavoro<\/strong> a tutela degli educatori.<\/p>\n<p><em>&#8220;Siamo orgogliosi<\/em> \u2013 conclude l&#8217;assessore Caracciolo \u2013 <em>che la Calabria sia tra le prime Regioni in Italia ad aver emanato linee guida in un settore cos\u00ec delicato e strategico per lo sviluppo del territorio, ponendosi all&#8217;avanguardia nella promozione di una cultura pedagogica fondata sulla cura, sulla prevenzione e sulla corresponsabilit\u00e0 educativa tra istituzioni, famiglie e comunit\u00e0&#8221;.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; In Calabria si punta a contrastare la povert\u00e0 educativa legata all&#8217;infanzia, come mai fatto prima d&#8217;ora, con l&#8217;approvazione delle linee d&#8217;indirizzo per il sistema di tutela e prevenzione dei bambini. Un documento strategico che punta a rafforzare i servizi rivolti alla prima infanzia contrastando il rischio di maltrattamenti, abusi e condotte inappropriate nei [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":242581,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-262340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/262340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=262340"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/262340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/242581"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=262340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=262340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=262340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}