{"id":262342,"date":"2025-06-24T13:00:15","date_gmt":"2025-06-24T11:00:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=262342"},"modified":"2025-06-24T12:10:39","modified_gmt":"2025-06-24T10:10:39","slug":"matteo-vinci-ucciso-da-unautobomba-annullato-con-rinvio-lergastolo-per-rosaria-mancuso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/matteo-vinci-ucciso-da-unautobomba-annullato-con-rinvio-lergastolo-per-rosaria-mancuso\/","title":{"rendered":"Matteo Vinci ucciso da un&#8217;autobomba, annullato con rinvio l&#8217;ergastolo per Rosaria Mancuso"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; La Corte di Cassazione ha disposto l&#8217;annullamento con rinvio della condanna all&#8217;ergastolo per <strong>Rosaria Mancuso<\/strong>, accusata di essere una dei mandanti dell&#8217;omicidio di<a href=\"https:\/\/quicosenza.it\/news\/?s=matteo+vinci\"> Matteo Vinci,<\/a> 42enne di Limbadi (Vv). Il biologo venne ucciso con una <strong>bomba sistemata nell&#8217;auto<\/strong> sulla quale viaggiava il <a href=\"https:\/\/quicosenza.it\/news\/calabria\/210977-salta-in-aria-lauto-di-matteo-vinci-muore-il-42enne-ferito-gravemente-il-padre\">9 aprile del 2018.<\/a> L&#8217;accusa riguarda anche il tentato omicidio del padre della vittima, Francesco, che si trovava con il figlio e rimase gravemente ferito.<\/p>\n<p>Rosaria Mancuso, in <strong>primo<\/strong> e <strong>secondo grado<\/strong> era stata <strong>condannata all&#8217;ergastolo<\/strong> insieme al <strong>genero Vito Barbara<\/strong>. La Suprema Corte ha accolto i rilievi dei difensori di Mancuso, gli avvocati Francesco Lojacono e Valerio Spigarelli (con la collaborazione degli avvocati Giovanni Vecchio e Francesco Capria, suoi precedenti difensori nelle fasi di merito) che hanno sostenuto la radicale assenza di elementi a suo carico. Per effetto della pronuncia di annullamento, in attesa del giudizio di rinvio, Rosaria Mancuso dovr\u00e0 essere <strong>immediatamente scarcerata<\/strong> per decorrenza dei termini massimi di custodia.<\/p>\n<p><strong>Confermata<\/strong> invece la sentenza di <strong>condanna al carcere a vita<\/strong> nei confronti di Vito Barbara (difeso dagli avvocati Dario Vannetiello e Fabrizio Costarella). Rigettati anche i ricorsi degli altri imputati, che erano stati ritenuti responsabili della detenzione di armi &#8211; Domenico Di Grillo e Lucia Di Grillo, marito e figlia di Rosaria Mancuso, difesi dagli avvocati Giovanni Vecchio, Francesco Capria, Gianfranco Giunta e Stefania Rania &#8211; condannati, rispettivamente, a 6 e 3 anni.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; La Corte di Cassazione ha disposto l&#8217;annullamento con rinvio della condanna all&#8217;ergastolo per Rosaria Mancuso, accusata di essere una dei mandanti dell&#8217;omicidio di Matteo Vinci, 42enne di Limbadi (Vv). Il biologo venne ucciso con una bomba sistemata nell&#8217;auto sulla quale viaggiava il 9 aprile del 2018. L&#8217;accusa riguarda anche il tentato omicidio [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":262343,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-262342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/262342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=262342"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/262342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/262343"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=262342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=262342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=262342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}