{"id":262403,"date":"2025-06-25T07:21:09","date_gmt":"2025-06-25T05:21:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=262403"},"modified":"2025-06-25T07:24:01","modified_gmt":"2025-06-25T05:24:01","slug":"giallo-sulla-morte-del-pescatore-ad-amendolara-si-indaga-per-omicidio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/giallo-sulla-morte-del-pescatore-ad-amendolara-si-indaga-per-omicidio\/","title":{"rendered":"Giallo sulla morte del pescatore ad Amendolara: si indaga per omicidio"},"content":{"rendered":"<p>CASTROVILLARI (CS) &#8211; \u00c8 stata eseguita ieri l\u2019autopsia sul corpo di <a href=\"https:\/\/quicosenza.it\/news\/ionio\/giallo-in-mare-si-indaga-su-francesco-vatano-pescatore-morto-al-largo-di-schiavonea\"><strong>Francesco Vatano<\/strong><\/a>, il pescatore di <strong>58 anni originario di Briatico<\/strong>, nel Vibonese, trovato cadavere <a href=\"https:\/\/quicosenza.it\/news\/ionio\/tragedia-in-mare-ad-amendolara-pescatore-muore-mentre-e-a-bordo-di-unimbarcazione\">alcuni giorni fa<\/a> al largo di Amendolara. In un primo momento si parlava di cause naturali ma ora, lo scenario che si apre \u00e8 di un <strong>presunto incidente sul lavoro<\/strong> avvenuto durante le operazioni di pesca. L\u2019esame autoptico avrebbe evidenziato un segno al collo compatibile con una morte per soffocamento meccanico e potrebbe essere stato causato da un pezzo di corda collegata alla rete che \u00e8 stata sequestrata.<\/p>\n<p>Il fascicolo aperto dalla Procura di Castrovillari contro ignoti \u00e8 per omicidio volontario. Sotto sequestro il peschereccio di 18 metri su cui Vatano si trovava come membro aggregato dell\u2019equipaggio. <strong>L&#8217;imbarcazione \u00e8 ferma a Corigliano Rossano <\/strong>e gli investigatori stanno anailzzando documenti di bordo, materiali, effetti personali e tutto ci\u00f2 che possa portare ad <strong>accertare cosa sia accaduto quel giorno in cui l&#8217;uomo \u00e8 caduto in mare<\/strong>. L\u2019autopsia ha <strong>escluso il malore<\/strong> e dunque alla base ci sarebbe stato un trauma. I familiari della vittima sono assistiti dagli avvocati Chiara Penna e Giuseppe Mario Aloi. Per l&#8217;esito dell&#8217;autopsia si dovr\u00e0 attendere 60 gioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASTROVILLARI (CS) &#8211; \u00c8 stata eseguita ieri l\u2019autopsia sul corpo di Francesco Vatano, il pescatore di 58 anni originario di Briatico, nel Vibonese, trovato cadavere alcuni giorni fa al largo di Amendolara. In un primo momento si parlava di cause naturali ma ora, lo scenario che si apre \u00e8 di un presunto incidente sul lavoro [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":262404,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19],"class_list":["post-262403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/262403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=262403"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/262403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/262404"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=262403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=262403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=262403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}