{"id":262835,"date":"2025-06-29T08:00:14","date_gmt":"2025-06-29T06:00:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=262835"},"modified":"2025-06-29T08:27:50","modified_gmt":"2025-06-29T06:27:50","slug":"colombia-arrestato-intermediario-della-ndrangheta-era-ricercato-dalla-giustizia-italiana","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/colombia-arrestato-intermediario-della-ndrangheta-era-ricercato-dalla-giustizia-italiana\/","title":{"rendered":"Colombia, arrestato un intermediario della &#8216;ndrangheta: era ricercato dalla giustizia italiana"},"content":{"rendered":"<p>BOGOT\u00c0 \u2013 La polizia colombiana ha arrestato nel comune di Caucasia, nel dipartimento di Antioquia, un uomo ritenuto un <strong>importante intermediario locale della \u2018ndrangheta<\/strong>. L\u2019operazione \u00e8 scattata in esecuzione di un\u2019allerta rossa dell\u2019Interpol, emessa su richiesta della magistratura italiana, che aveva spiccato un mandato d\u2019arresto per traffico di droga in concorso con altri reati.<\/p>\n<p>A confermare la notizia \u00e8 stato lo stesso <strong>comandante<\/strong> della <strong>polizia colombiana, Juan Pablo V\u00e9lez,<\/strong> con un messaggio diffuso su X: \u201c\u00c8 stato catturato un affiliato della mafia italiana!\u201d. Secondo le autorit\u00e0, l\u2019uomo coordinava una rete internazionale di narcotraffico che operava tra la <strong>Colombia, la Spagna e l\u2019Italia<\/strong>, in particolare con spedizioni di cocaina destinate a <strong>Genova<\/strong>, passando per la penisola iberica.<\/p>\n<p>\u201cIl soggetto era parte di un\u2019organizzazione con legami diretti con la \u2018<strong>ndrangheta calabrese<\/strong> e gestiva invii regolari di stupefacenti verso l\u2019Europa\u201d, ha spiegato V\u00e9lez, sottolineando il ruolo centrale dell\u2019arrestato nella catena logistica del traffico.\u00a0Il bilancio aggiornato delle operazioni condotte dalla polizia colombiana nel 2025 parla di 66 arresti eseguiti sulla base di allerta rosse dell\u2019Interpol, di cui 19 legati a crimini connessi al narcotraffico.<\/p>\n<p>L\u2019arresto rappresenta un nuovo colpo alle reti internazionali della criminalit\u00e0 organizzata italiana, sempre pi\u00f9 radicate nei circuiti globali del traffico di stupefacenti. <strong>Le autorit\u00e0 italiane hanno avviato le procedure per l\u2019estradizione.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOGOT\u00c0 \u2013 La polizia colombiana ha arrestato nel comune di Caucasia, nel dipartimento di Antioquia, un uomo ritenuto un importante intermediario locale della \u2018ndrangheta. L\u2019operazione \u00e8 scattata in esecuzione di un\u2019allerta rossa dell\u2019Interpol, emessa su richiesta della magistratura italiana, che aveva spiccato un mandato d\u2019arresto per traffico di droga in concorso con altri reati. A [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":262836,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[22],"tags":[19],"class_list":["post-262835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dal-mondo","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/262835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=262835"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/262835\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/262836"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=262835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=262835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=262835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}