{"id":262970,"date":"2025-07-06T00:00:12","date_gmt":"2025-07-05T22:00:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=262970"},"modified":"2025-07-06T00:59:18","modified_gmt":"2025-07-05T22:59:18","slug":"saracenix-nel-pollino-il-gioco-urbano-punta-ad-educare-e-valorizzare-il-territorio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/saracenix-nel-pollino-il-gioco-urbano-punta-ad-educare-e-valorizzare-il-territorio\/","title":{"rendered":"Saracenix, nel Pollino il gioco urbano punta ad educare e valorizzare il territorio"},"content":{"rendered":"<p>SARACENA (CS) &#8211; Educare e puntare alla <strong>valorizzazione del territorio<\/strong> attraverso il gioco urbano. \u00c8 staton questo il focus che ha guidato Saracenix, il progetto, inseriro all&#8217;interno dell\u2019iniziativa Benessere In Comune, organizzato dal Comune di Saracena negli scorsi giorni.\u00a0L&#8217;obiettivo \u00e8 stato quello di stimolare un <strong>nuovo attivismo giovanile,<\/strong> rafforzando i rapporti sociali tra genitori e figli, e generazioni diverse, favorendo, inoltre, una <strong>maggiore e migliore conoscenza del territorio<\/strong> e del contesto locale.<\/p>\n<p>Come? Attraverso un <strong>gioco urbano<\/strong> che ha messo in campo <strong>attivit\u00e0 ludico didattiche<\/strong> non fini a s\u00e8 stesse ma che hanno dato output concreti e utili alla valorizzazione del potenziale inespresso del paese, riutilizzabili dall\u2019amministrazione locale per la progettazione di vere e proprie campagne di marketing e prodotti turistici.<\/p>\n<p>Il programma \u00e8 stato ricco di attivit\u00e0 laboratoriali educative a tema creativo, ludico ed ecologiche con un focus sulla valorizzazione del patrimonio materiale ed immateriale del borgo del Pollino. I bambini e le bambine di Saracena che sono state coinvolte si sono trasformati in ricercatori e divulgatori, costruendo mappe del patrimonio e itinerari per i viaggiatori di domani. \u00c8 stato costruito cos\u00ec un <strong>processo di valorizzazione territoriale e comunitario<\/strong> che ha visto coinvolta tutta la popolazione con una <strong>partecipazione intergenerazionale. <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SARACENA (CS) &#8211; Educare e puntare alla valorizzazione del territorio attraverso il gioco urbano. \u00c8 staton questo il focus che ha guidato Saracenix, il progetto, inseriro all&#8217;interno dell\u2019iniziativa Benessere In Comune, organizzato dal Comune di Saracena negli scorsi giorni.\u00a0L&#8217;obiettivo \u00e8 stato quello di stimolare un nuovo attivismo giovanile, rafforzando i rapporti sociali tra genitori e [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":262972,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-262970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/262970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=262970"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/262970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/262972"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=262970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=262970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=262970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}