{"id":26313,"date":"2013-10-01T08:30:04","date_gmt":"2013-10-01T06:30:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26313"},"modified":"2023-01-17T13:23:50","modified_gmt":"2023-01-17T12:23:50","slug":"10795-nascondeva-proiettili-calibro-357-nelle-mutande-arrestato-rumeno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/10795-nascondeva-proiettili-calibro-357-nelle-mutande-arrestato-rumeno\/","title":{"rendered":"Nascondeva proiettili calibro 357 nelle mutande, arrestato rumeno"},"content":{"rendered":"<p class=\"p1\">RENDE &#8211; Passeggiava come tanti giovani coetanei a Roges.<\/p>\n<p>  <!--more-->  <\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Ma ai carabinieri la sua andatura pareva alquanto sospetta. Un amico lo seguiva contromano a passo d&#8217;uomo con un&#8217;auto di grossa cilindrata con targa straniera. I due ragazzi dell&#8217;est sono stati cos\u00ec fermati dai militari per un controllo. In via Pertini sono le 23.40 e c&#8217;\u00e8 ancora un disceto via vai di auto nonostante sia un trqnauillo luned\u00ec di fine estate. Eppure nonostante ci\u00f2 il movimento azzardato del 27enne rumeno, che avrebbe lanciato la rivoltella vicino ad un albero, non \u00e8 passato inosservato. Il giovane infatti alla vista delle forze dell&#8217;ordine si sarebbe agilmente liberato di quel pericoloso fardello che portava con s\u00e8: un revolver calibro 357 magnum. Un gesto che ha insospettito i militari che rovistando tra i cespugli hanno cos\u00ec trovato la pistola custodita dal 27enne. Zaharia Ionut, originario di Piatra Neamt, ma da tempo residente a Decollatura nel catanzarese \u00e8 stato cos\u00ec arrestato dai carabinieri del comando di Rende. Il giovane, incensurato colto in flagranza di porto abusivo d&#8217;armi per quel calibro 357 magnum, Astra 960, gi\u00e0 caricato con sei proiettili \u00e8 finito in manette. Ma c&#8217;\u00e8 di pi\u00f9. Zaharia nelle mutande nascondeva altri proiettili, dieci per l&#8217;esattezza, che sono stati prelevati dai militari e posti sotto sequestro. L&#8217;amico \u00e8 stato perquisito cos\u00ec come la sua Bmw scintillante, ma a suo carico i carabinieri non hanno trovato nulla di illecito, a parte, la muta per aver imboccato la strada contromano. Zhahia invece \u00e8 attualmente detenuto in camera di sicurezza in attesa del rito direttissimo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Passeggiava come tanti giovani coetanei a Roges.<\/p>\n","protected":false},"author":22,"featured_media":26314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,44],"tags":[],"class_list":["post-26313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26313"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26314"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}