{"id":26317,"date":"2013-10-01T11:21:41","date_gmt":"2013-10-01T09:21:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26317"},"modified":"2023-01-17T13:23:50","modified_gmt":"2023-01-17T12:23:50","slug":"10797-cosenza-ambientalista-parte-la-differenziata-spariscono-i-cassonetti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/10797-cosenza-ambientalista-parte-la-differenziata-spariscono-i-cassonetti\/","title":{"rendered":"Cosenza ecologista: parte la differenziata, spariscono i cassonetti"},"content":{"rendered":"<p>COSENZA &#8211; Due secchielli e qualche busta.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Questa l&#8217;innovazione dei tecnici ambientali bruzi. Il triumvirato composto da Comune di Cosenza, Conai ed Ecologia Oggi ha lanciato a partire da oggi la nuova campagna di raccolta differenziata in citt\u00e0. Poche informazioni, rilasciate solo a casalinghe, anziani e disoccupati. Per la Cosenza che lavora nulla \u00e8 dato sapere, non merita neanche quei due bidoni. Negli orari in cui si distribuiscono i preziosi secchielli non ci sono, allora terranno l&#8217;immondizia in casa. Eppure anche loro pagano la TARSU. Stamattina i cosentini del centro citt\u00e0 al loro risveglio non hanno ritrovato pi\u00f9 i cassonetti strabordanti di immondizia, n\u00e8 quelli di metallo, n\u00e8 quei sporchi parellelepipedi color bianco o blu. Tutto sparito. Al loro posto le macchine che approfittano dei nuovi stalli in cui parcheggiare ora che non ci sono pi\u00f9 i cassonetti. Dove si butta l&#8217;immondizia? A rispondere con dovizia di dettagli \u00e8 un numero telefonico dedicato alle informazioni agli utenti, lo 0984\/24685 degli addetti dell&#8217;Ufficio Start Up di via Galeazzo da Tarsia che Ecologia gestisce in collaborazione con il CONAI.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">E s\u00ec Ecologia Oggi, l&#8217;azienda addetta alla comunicazione della rivoluzione culturale cosentina in materia di rifiuti. La stessa che contattata ripetutamente dalla nostra redazione ha rifiutato, se non ignorato, la disponibilit\u00e0 offerta gratuitamente dalla testata QuiCosenza, cui editore \u00e8 particolarmente sensibile alle tematiche ambientaliste, di diffondere informazioni per promuovere il passaggio alla raccolta differenziata. Sicuramente il triumvirato sapr\u00e0 entrare in cottatto con i cosentini e spingerli ad accettare la differenziata, ma ad oggi non risulta essere cos\u00ec. Sono diverse le famiglie che non hanno ricevuto alcuna informativa. Diversi i condomini che non sanno pi\u00f9 dove mettere i sacchetti. &#8220;Dovranno chiedere all&#8217;amministratore condominiale di presentare istanza per avere i carrellati, &#8211; afferma l&#8217;operatore da via Galeazzo da Tarsia, nel centro storico &#8211; chi non ce l&#8217;ha deve <strong>buttare l&#8217;umido, Marted\u00ec, Gioved\u00ec e Domenica, nel secchiello marrone. La plastica con il barattolame invece sar\u00e0 messa direttamente nei sacchetti da porre sul ciglio del marciapiede. Il vetro dovr\u00e0 essere portato in strada nel secchiello grigio al Sabato, mentre nello stesso secchiello al Venerd\u00ec verr\u00e0 riposta la carta e al Luned\u00ec tutto ci\u00f2 che non \u00e8 riciclabile. Chi non ha n\u00e8 secchielli, n\u00e8 sacchetti pu\u00f2 ritirarli tutti i giorni dalle 9.30 alle 13.00 e dalle 14.30 alle 18.00 il sabato dalle 9.30 alle 12.00 nei nostri uffici&#8221;<\/strong>. E poi? &#8220;Dopo &#8211; sentenzia con imbarazzo l&#8217;operatore &#8211; per vincolo di legge dovrebbero essere consegnati al pi\u00f9 vicino centro di stoccaggio per essere ripuliti ed entrare nel circolo del riciclo. Ma in Calabria, che io sappia non ne esistono&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Due secchielli e qualche busta.<\/p>\n","protected":false},"author":22,"featured_media":26318,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-26317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26317"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26318"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}