{"id":263505,"date":"2025-07-05T18:03:56","date_gmt":"2025-07-05T16:03:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=263505"},"modified":"2025-07-05T18:03:56","modified_gmt":"2025-07-05T16:03:56","slug":"incidente-sulla-statale-18-a-fuscaldo-tre-mezzi-coinvolti-tra-cui-unautomedica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/incidente-sulla-statale-18-a-fuscaldo-tre-mezzi-coinvolti-tra-cui-unautomedica\/","title":{"rendered":"Incidente sulla Statale 18 a Fuscaldo, tre mezzi coinvolti tra cui un&#8217;automedica"},"content":{"rendered":"<p>FUSCALDO (CS) &#8211; Dopo il violento impatto avvenuto nella tarda serata a <a href=\"https:\/\/quicosenza.it\/news\/tirreno\/violento-scontro-sulla-statale-18-impatto-tra-un-furgone-e-due-auto-cinque-feriti-tra-cui-un-bambino\">Scalea<\/a>, un altro incidente stradale si \u00e8 verificato in tarda <strong>mattinata sulla Statale 18 Tirrena inferiore<\/strong>, in provincia di Cosenza, <strong>nel territorio di Fuscaldo<\/strong>. Sarebbero tre i mezzi coinvolti: un <strong>Suv MG, un furgoncino e un&#8217;automedica della Misericordia<\/strong>. Secondo quanto emerso non ci sarebbero state gravi conseguenze per gli occupanti delle vetture, ma l&#8217;incidente ha creato rallentamenti al traffico veicolare. Al vaglio delle forze dell&#8217;ordine la dinamica del sinistro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FUSCALDO (CS) &#8211; Dopo il violento impatto avvenuto nella tarda serata a Scalea, un altro incidente stradale si \u00e8 verificato in tarda mattinata sulla Statale 18 Tirrena inferiore, in provincia di Cosenza, nel territorio di Fuscaldo. Sarebbero tre i mezzi coinvolti: un Suv MG, un furgoncino e un&#8217;automedica della Misericordia. Secondo quanto emerso non ci [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":263506,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-263505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/263505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=263505"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/263505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/263506"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=263505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=263505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=263505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}