{"id":264031,"date":"2025-07-12T06:30:17","date_gmt":"2025-07-12T04:30:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=264031"},"modified":"2025-07-12T06:39:48","modified_gmt":"2025-07-12T04:39:48","slug":"bollino-rosso-anche-nel-secondo-weekend-luglio-atteso-traffico-intenso-su-a2-statale-18-e-106-jonica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/bollino-rosso-anche-nel-secondo-weekend-luglio-atteso-traffico-intenso-su-a2-statale-18-e-106-jonica\/","title":{"rendered":"Bollino rosso anche nel secondo weekend di luglio. Atteso traffico intenso su A2, Statale 18 e 106 Jonica"},"content":{"rendered":"<p>COSENZA &#8211; Nel s<strong>econdo fine settimana di luglio lungo l<\/strong>a rete stradale e autostradale di Anas (Gruppo Fs Italiane) \u00e8<strong> atteso traffico in costante aumento con spostamenti in crescita dai grandi centri urbani verso le localit\u00e0 di villeggiatura, di mare al Sud e di montagna a nord e verso i confini di Stato<\/strong>. Come nello scorso fine settimana le partenze si concentreranno nel pomeriggio e nelle prime ore della serata di oggi in cui \u00e8 previsto bollino rosso e nel pomeriggio e nella serata di domenica per i rientri. \u201cAnas \u2013 ha dichiarato l\u2019Amministratore delegato Claudio Andrea Gemme &#8211; \u00e8 impegnata a semplificare la gestione del traffico che si intensificher\u00e0 ancora di pi\u00f9 nelle prossime settimane con <strong>l\u2019ottimizzazione dei cantieri per completarli, ove possibile, prima dell\u2019esodo estivo. Abbiamo potenziato i pres\u00ecdi su tutto il territorio nazionale.<\/strong> L\u2019obiettivo \u00e8 dare agli utenti strade ancora pi\u00f9 sicure e con migliori tempi di percorrenza\u201d.<\/p>\n<p>Per consentire la fluidit\u00e0 del traffico, Anas garantir\u00e0 pres\u00ecdi di personale sull\u2019intera rete stradale e autostradale, in particolar modo in corrispondenza dei cantieri inamovibili. Per quanto riguarda la nostra regione,\u00a0l\u2019<strong>intensificazione della circolazione potr\u00e0 riguardare i principali itinerari turistici<\/strong>: l&#8217;<strong>Autostrada A2 \u201cAutostrada del Mediterraneo\u201d<\/strong> che attraversa Campania, Basilicata e Calabria e le <strong>Statali 106 \u201cJonica\u201d e 18 \u201cTirrena Inferiore\u201d<\/strong>. Il divieto di transito dei veicoli pesanti sar\u00e0 in vigore da domani sabato dalle ore 8 alle 16, e domenica dalle 7 alle 22. La presenza su strada di Anas \u00e8 di circa 2.500 risorse in turnazione, costituite da personale tecnico e di esercizio, oltre al personale delle Sale Operative Territoriali e della Sala Situazioni Nazionale che assicurano il monitoraggio del traffico in tempo reale h 24.<\/p>\n<h3><u>I consigli agli automobilisti<\/u><\/h3>\n<p>Anas invita gli automobilisti a <strong>valutare fasce orarie alternative per il rientro<\/strong>, in preferenza <strong>al mattino o in tarda serata,<\/strong> per evitare i momenti di maggiore congestione, e raccomanda di evitare le ore pi\u00f9 calde, di viaggiare con veicoli in buone condizioni e portare con s\u00e9 adeguate scorte d\u2019acqua.\u00a0Si ricorda che l<strong>e corsie di emergenza sono destinate esclusivamente ai mezzi di soccorso e alle Forze dell\u2019Ordine<\/strong>. Anche in situazioni di traffico copioso \u00e8 in ogni caso sempre interdetta e preclusa all\u2019utenza la possibilit\u00e0 di utilizzarle.\u00a0Anas ricorda, inoltre, le campagne di prevenzione per la sicurezza stradale \u201cQuando guidi, Guida e Basta\u201d e per il rischio incendi \u201cLa strada non \u00e8 un posacenere\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Nel secondo fine settimana di luglio lungo la rete stradale e autostradale di Anas (Gruppo Fs Italiane) \u00e8 atteso traffico in costante aumento con spostamenti in crescita dai grandi centri urbani verso le localit\u00e0 di villeggiatura, di mare al Sud e di montagna a nord e verso i confini di Stato. Come nello [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":174642,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-264031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/264031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=264031"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/264031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/174642"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=264031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=264031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=264031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}