{"id":264238,"date":"2025-07-14T07:22:15","date_gmt":"2025-07-14T05:22:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=264238"},"modified":"2025-07-14T07:22:15","modified_gmt":"2025-07-14T05:22:15","slug":"convocata-lassemblea-provinciale-del-partito-democratico-di-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/convocata-lassemblea-provinciale-del-partito-democratico-di-cosenza\/","title":{"rendered":"Convocata l&#8217;assemblea provinciale del Partito democratico di Cosenza"},"content":{"rendered":"<p>RENDE &#8211; Si terr\u00e0 all&#8217;hotel President di Rende domani, marted\u00ec<strong> 15 luglio<\/strong> alle 18.30, l\u2019Assemblea provinciale di insediamento alla quale parteciperanno i membri elettivi in numero pari a 62, oltre ai membri individuati dall\u2019articolo 13 dello Statuto tra i quali: i sindaci iscritti al PD, i consiglieri regionali, il Capogruppo alla Provincia, la rappresentante delle democratiche calabresi, i componenti della commissione per il congresso provinciale. Attesa la partecipazione del segretario regionale <strong>Nicola Irto. <\/strong><\/p>\n<p>L&#8217;assemblea di domani segue l&#8217;elezione del sindaco di Celico, Matteo Lettieri, a segretario provinciale del PD, avendo conquistato la maggioranza dei delegati \u2013 34 contro i 26 attribuiti allo sfidante, Pino Le Fosse. L\u2019assemblea del 15 luglio rappresenter\u00e0 non solo l\u2019atto formale di proclamazione, ma anche il primo banco di prova per definire le linee politiche del nuovo corso provinciale, in un momento cruciale per il centrosinistra calabrese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Si terr\u00e0 all&#8217;hotel President di Rende domani, marted\u00ec 15 luglio alle 18.30, l\u2019Assemblea provinciale di insediamento alla quale parteciperanno i membri elettivi in numero pari a 62, oltre ai membri individuati dall\u2019articolo 13 dello Statuto tra i quali: i sindaci iscritti al PD, i consiglieri regionali, il Capogruppo alla Provincia, la rappresentante delle [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":264239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-264238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/264238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=264238"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/264238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/264239"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=264238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=264238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=264238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}