{"id":264380,"date":"2025-07-15T11:38:41","date_gmt":"2025-07-15T09:38:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=264380"},"modified":"2025-07-15T11:51:07","modified_gmt":"2025-07-15T09:51:07","slug":"zumpano-arrestato-il-presunto-autore-della-rapina-alle-poste","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/zumpano-arrestato-il-presunto-autore-della-rapina-alle-poste\/","title":{"rendered":"Zumpano, arrestato il presunto autore della rapina alle Poste"},"content":{"rendered":"<p>ZUMPANO (CS) &#8211; \u00c8 stato <strong>arrestato<\/strong> il <strong>presunto autore<\/strong> dell&#8217;ultima <strong>rapina<\/strong> effettuata presso le <a href=\"https:\/\/quicosenza.it\/news\/provincia\/rapinato-lufficio-postale-di-zumpano-il-malvivente-armato-ha-portato-via-circa-90mila-euro\" target=\"_blank\" rel=\"noopener\"><strong>Poste di Zumpano.<\/strong><\/a> Si tratta, a quanto emerso dalle indagini, di un <strong>latitante calabrese.<\/strong> Lo comunica l&#8217;amministrazione comunale del comune cosentino ringraziando l&#8217;arma dei carabinieri di Celico guidati dal comandante maresciallo Eugenio Gamba, e la polizia locale di Zumpano, sotto la guida del comandante dott. Andrea Donato, per il lavoro svolto ed il prezioso lavoro investigativo eseguito.<\/p>\n<p>Si tratta dell&#8217;uomo<strong>, originario del cosentino,<\/strong> latitante da quasi un mese e <strong>ricercato con due mandati di cattura<\/strong> emessi dall&#8217;Autorit\u00e0 Giudiziaria calabrese per reati simili, tra cui la <a href=\"https:\/\/quicosenza.it\/news\/italia\/era-ricercato-per-una-tentata-rapina-alle-poste-latitante-cosentino-arrestato-in-abruzzo\"><strong>tentata rapina compiuta all&#8217;Ufficio Postale di Villa Tordinia in Abruzzo<\/strong><\/a>. Nonostante fosse sottoposto alla misura di prevenzione della sorveglianza speciale con obbligo di soggiorno nel proprio Comune di residenza, l&#8217;arrestato si era reso irreperibile fino all&#8217;identificazione e alla cattura avvenuta a Teramo dopo un lungo appostamento.<\/p>\n<p>Il Sindaco di Zumpano, Avv. Fabrizio Fabiano, ha dichiarato: &#8220;<em>Siamo estremamente soddisfatti del lavoro svolto dalle forze dell&#8217;ordine, che hanno dimostrato un&#8217;eccellente coordinazione e professionalit\u00e0. La <strong>sicurezza dei nostri cittadini \u00e8 una priorit\u00e0<\/strong> e questi risultati testimoniano l&#8217;impegno costante nella lotta contro la criminalit\u00e0. Ringraziamo tutti coloro che hanno contribuito a questa operazione, in particolare i Carabinieri di Celico e la Polizia Locale di Zumpano, per la loro dedizione e prontezza nel garantire un ambiente sicuro per la nostra comunit\u00e0.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ZUMPANO (CS) &#8211; \u00c8 stato arrestato il presunto autore dell&#8217;ultima rapina effettuata presso le Poste di Zumpano. Si tratta, a quanto emerso dalle indagini, di un latitante calabrese. Lo comunica l&#8217;amministrazione comunale del comune cosentino ringraziando l&#8217;arma dei carabinieri di Celico guidati dal comandante maresciallo Eugenio Gamba, e la polizia locale di Zumpano, sotto la [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":226166,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-264380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/264380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=264380"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/264380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/226166"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=264380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=264380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=264380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}