{"id":264402,"date":"2025-07-19T11:15:32","date_gmt":"2025-07-19T09:15:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=264402"},"modified":"2025-07-19T10:53:05","modified_gmt":"2025-07-19T08:53:05","slug":"fuga-sanitaria-la-calabria-e-al-primo-posto-il-20-dei-pazienti-si-fa-curare-altrove","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/fuga-sanitaria-la-calabria-e-al-primo-posto-il-20-dei-pazienti-si-fa-curare-altrove\/","title":{"rendered":"Fuga sanitaria: Calabria prima regione dove si &#8220;scappa&#8221; per farsi curare&#8230; nei super ospedali del Nord"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Aumentano i ricoveri<\/strong> negli ospedali italiani. Nel 2023 sono cresciuti del <strong>+4,3%<\/strong> rispetto al 2022, <strong>7 milioni e 670mila <\/strong>in tutto con pazienti che in molti casi non restano nella regione di residenza. \u00c8 quanto emerge dai dati del Rapporto annuale sull&#8217;attivit\u00e0 di ricovero ospedaliero Sdo 2023, realizzato dal<strong> mistero della Salute.<\/strong><\/p>\n<p>La <strong>fuga sanitaria<\/strong> resta forte e stabile: l&#8217;8,5% dei ricoveri riguarda pazienti che si spostano in un&#8217;altra regione ed in questo esodo la <strong>Calabria \u00e8 al primo posto.<\/strong> Nella nostra regione, infatti, oltre il <strong>20% delle persone<\/strong> sceglie di <strong>scappare per farsi curare altrove<\/strong>. La <strong>Lombardia<\/strong> \u00e8 la regione che attrae e accoglie di pi\u00f9, seguita da <strong>Emilia-Romagna e Toscana.<\/strong><\/p>\n<h3>La mobilit\u00e0 sanitaria vale 2,8 miliardi di euro<\/h3>\n<p>La mobilit\u00e0 sanitaria (secondo quanto stimato dall&#8217;Aegnzia nazionale dei sevizi sanitari regionali) <strong>vale poco pi\u00f9 di 2,8 miliardi di euro<\/strong>. Dopo la Calabria, l<strong>e regioni da cui pi\u00f9 pazienti scappano per farsi curare altrove, in base ai grafici riportati dal Rapporto Sdo sono Molise, Basilicata, Campania<\/strong>. Ad attrarre maggiormente <strong>sono regioni del Nord come Lombardia, Emilia-Romagna e Toscana<\/strong>. Il Drg (o Raggruppamento Omogeneo di Diagnosi) pi\u00f9 frequente \u00e8 il parto vaginale. I tagli sono cesarei in calo, ma ancora lontani dagli standard: <strong>nel 2023 sono il 32% dei parti, in calo costante dal 2018 (-3%).<\/strong><\/p>\n<p><strong>I ricoveri per acuti coprono il 95% dell&#8217;attivit\u00e0 ospedaliera<\/strong> e di questi il 73% avviene in regime ordinario, il<strong> 22% in day hospital; la degenza media \u00e8 di circa 7 giorni, in calo rispetto al 2020 (7,5)<\/strong>. I dati mostrano il boom della riabilitazione (+10% in regime ordinario e +8% in day hospital). Il 75% dei ricoveri per acuti e l&#8217;81% delle giornate avviene in strutture pubbliche. Al contrario i privati sono protagonisti nella riabilitazione: il 75% \u00e8 erogata da strutture accreditate. Migliorano, infine, gli indicatori sulle performance organizzative: la degenza media pre-operatoria scende a 1,6 giorni, segno di maggiore efficienza ospedaliera.<\/p>\n<h3>In Italia 21 &#8216;super ospedali&#8217;, domina il Nord e solo 2 al Sud<\/h3>\n<p>&#8220;La spina dorsale dei grandi ospedali italiani si ferma a Roma.<strong> I maxi poli di eccellenza della nostra Sanit\u00e0 che curano pi\u00f9 pazienti e gestiscono i casi pi\u00f9 complessi attirando italiani dalle altre Regioni restano concentrati al Centro Nord<\/strong>&#8220;. La mappa delle eccellenze sanitarie italiane mostra ancora una volta un&#8217;Italia divisa in due. Secondo i dati aggiornati al 2023 sulla base delle schede di dimissioni ospedaliere, <strong>elaborati dal Il Sole 24 ore,<\/strong> i grandi ospedali che trattano i casi pi\u00f9 complessi e attraggono pazienti da altre Regioni, sono concentrati al Centro-Nord. <strong>Su 21 &#8220;super ospedali&#8221;, ben 12 si trovano al Nord, 7 al Centro e soltanto 2 al Sud<\/strong>. In cima alla classifica svettano l<strong>&#8216;Irccs Galeazzi di Milano<\/strong>, l&#8217;<strong>Humanitas di Rozzano e il San Raffaele di Milano<\/strong>. I tre giganti lombardi hanno i punteggi pi\u00f9 alti in termini di attrattivit\u00e0 e complessit\u00e0 dei casi trattati. Segue l&#8217;<strong>ospedale Sant&#8217;Orsola di Bologna<\/strong>, poi tre strutture venete (Verona, Don Calabria e Padova), tre toscane (Pisa, Siena, Firenze Careggi) e <strong>tre romane<\/strong> (Gemelli, Campus Biomedico e San Camillo). Completano il quadro il <strong>Mauriziano di Torino,<\/strong> l&#8217;A<strong>zienda ospedaliero universitaria di Alessandria, il San Martino di Genova e l&#8217;Aou delle Marche<\/strong>.<\/p>\n<p>Al Sud si distinguono solo due strutture: l&#8217;<strong>Azienda ospedaliera dei Colli di Napoli e la Casa Sollievo della Sofferenza di San Giovanni Rotondo, in Puglia<\/strong>. Una disparit\u00e0 evidente che alimenta il fenomeno dei &#8220;viaggi della speranza&#8221;, ovvero lo spostamento di migliaia di pazienti dal Sud verso il Nord in cerca di cure specialistiche. <strong>L&#8217;Istituto Clinico Humanitas di Rozzano conferma quindi gli ottimi risultat<\/strong>i: era gi\u00e0 stato indicato come migliore ospedale d&#8217;Italia, insieme a due strutture pubbliche, il Careggi di Firenze e l&#8217;ospedale di Ancona, dal Programma Nazionale Esiti elaborato dall&#8217;Agenzia nazionale per i servizi sanitari regionali (Agenas). In questo caso, i dati, anche essi del 2023, prendevano in esame i livelli di performance raggiunti in base a una serie di indicatori relativi a procedure sanitarie come operazione al femore, bypass coronarico e l&#8217;intervento chirurgico per tumore alla mammella.<\/p>\n<h3>Ma per il ministero della Salute nessuna classifica<\/h3>\n<div id=\"txt_cont\">&#8220;In relazione alla m<strong>appatura dei migliori ospedali d&#8217;Italia, si precisa che il ministero della Salute non ha redatto n\u00e9 pubblicato alcuna mappa o classifica delle strutture ospedaliere<\/strong>&#8220;: lo rileva lo stesso ministero in una nota. &#8220;I dati circolati su alcuni organi di informazione &#8211; prosegue il ministero &#8211; non hanno attinenza con le elaborazioni del ministero della Salute finalizzate a individuare ospedali di rilievo nazionale per i quali sono ancora in fase di perfezionamento le metodologie di analisi&#8221;.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Aumentano i ricoveri negli ospedali italiani. Nel 2023 sono cresciuti del +4,3% rispetto al 2022, 7 milioni e 670mila in tutto con pazienti che in molti casi non restano nella regione di residenza. \u00c8 quanto emerge dai dati del Rapporto annuale sull&#8217;attivit\u00e0 di ricovero ospedaliero Sdo 2023, realizzato dal mistero della Salute. La [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":257948,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-264402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/264402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=264402"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/264402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/257948"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=264402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=264402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=264402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}