{"id":26446,"date":"2013-10-08T10:00:52","date_gmt":"2013-10-08T08:00:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26446"},"modified":"2023-01-17T13:23:58","modified_gmt":"2023-01-17T12:23:58","slug":"10866-resta-senza-nome-il-cadavere-della-donna-trovata-a-mirto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/10866-resta-senza-nome-il-cadavere-della-donna-trovata-a-mirto\/","title":{"rendered":"Resta senza nome il cadavere della donna trovato a Mirto"},"content":{"rendered":"<p style=\"text-align: justify;\">MIRTO CROSIA &#8211; Il cadavere era stato ritrovato cinque giorni fa da due anziani in un uliveto che collega il centro abitato di Mirto Crosia con il lungomare di Centofontane.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">I primi elementi raccolti sembrano far propendere per una morte dovuta a cause naturali e per questo motivo, con tutta probabilit\u00e0, non si proceder\u00e0 ad effettuare l&#8217;esame autoptico anche perch\u00e8 il cadavere, trovato in avanzato stato di decomposizione, non porterebbe secondo gli inquirenti, elementi utili alle indagini.&nbsp;Secondo un primo esame esterno, il corpo non presentava segni di violenza e la posizione in cui \u00e8 stato trovato ricondurrebbe la causa della morte ad un malore. La donna infatti \u00e8 stata trovata accucciata, con in mano ancora la borsetta e con addosso, un pantalone ed una maglia. Proprio l&#8217;abbigliamento potrebbe svelare la sua identit\u00e0 e l&#8217;ipotesi \u00e8 che si tratti di una donna 32enne, polacca, che in molti avrebbero visto in giro nel piccolo centro dello Jonio Cosentino. Ad attendere l&#8217;accertamento dell&#8217;dentit\u00e0 della donna, il fratello che vive a Pietrapaola e che aspetta di capire se quella donna \u00e8 sua sorella e piangerla assieme ai suoi familiari.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MIRTO CROSIA &#8211; Il cadavere era stato ritrovato cinque giorni fa da due anziani in un uliveto che collega il centro abitato di Mirto Crosia con il lungomare di Centofontane.<\/p>\n","protected":false},"author":19,"featured_media":26447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-26446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26446"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26447"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}