{"id":264515,"date":"2025-07-20T13:00:08","date_gmt":"2025-07-20T11:00:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=264515"},"modified":"2025-07-20T17:58:26","modified_gmt":"2025-07-20T15:58:26","slug":"rischio-incendi-appello-del-vescovo-della-diocesi-di-san-marco-argentano-scalea-responsabilita-di-tutti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rischio-incendi-appello-del-vescovo-della-diocesi-di-san-marco-argentano-scalea-responsabilita-di-tutti\/","title":{"rendered":"Rischio incendi: appello del vescovo della diocesi di San Marco Argentano-Scalea: \u00abresponsabilit\u00e0 di tutti\u00bb"},"content":{"rendered":"<p>SAN MARCO ARGENTANO (CS) &#8211; Il vescovo della Diocesi San Marco Argentano &#8211; Scalea, <strong>Stefano Rega<\/strong>, invia un messaggio di <strong><em>\u201cresponsabilit\u00e0 condivisa contro il flagello degli incendi\u201d.<\/em><\/strong> Monsignore di fronte al difficile periodo che il territorio calabrese sta vivendo per l&#8217;emergenza legata agli incendi boschivi, fa appello a tutti, indistintamente.<\/p>\n<p><em>&#8220;Dati recenti indicano che, dal 1\u00b0 gennaio a giugno 2025, la Calabria ha registrato il <strong>70% degli incendi verificatisi in Italia<\/strong>, con<strong> numerosi roghi proprio all\u2019interno della diocesi,<\/strong> sia lungo la fascia tirrenica che nelle aree interne del Pollino<\/em> &#8211; scrive il vescovo Rega &#8211; <em>\u00c8 doloroso constatare che spesso si tratta di<strong> atti dolosi,<\/strong> di cui \u00e8 difficile perfino intuire il motivo, considerando i <strong>danni devastanti e il rischio per vite umane<\/strong>\u201d. <\/em><\/p>\n<h3>Rischio incendi, la lettera del vescovo: &#8220;Serve maggiore responsabilit\u00e0&#8221;<\/h3>\n<p>Questo il motivo che ha spinto il vescovo rega a mandare un richiamo al senso civico e alla cura del creato. Monsignor rega invita cos\u00ec &#8220;tutti, credenti e non, ad <strong>assumersi una maggiore responsabilit\u00e0 verso la salvaguardia del territorio<\/strong> e delle aree boschive, evidenziando il valore unico di ecosistemi come quello dei pini loricati, patrimonio naturale raro e fragile. Non basta la prevenzione &#8211; sottolinea &#8211; serve un nuovo sguardo: uno sguardo che contempli, rispetti, protegga\u201d.<\/p>\n<p>Citazioni tratte dalla Laudato Si\u2019 di Papa Francesco e dagli scritti dei grandi santi, come Sant\u2019Agostino, San Bernardo di Chiaravalle e San Francesco d\u2019Assisi, scandiscono il messaggio del Vescovo, che propone una vera e propria conversione ecologica e spirituale. \u201c<em>Il creato ci parla di Dio. I nostri boschi, le montagne, i sentieri sono luoghi di bellezza e contemplazione, ma anche spazi educativi, opportunit\u00e0 per riscoprire la nostra relazione con la terra e con il Creatore\u201d. <\/em><\/p>\n<p>Infine un\u2019esortazione chiara da parte del vescovo:<em> \u201cNon fermiamoci solo alla lotta contro gli incendi.<strong> Impariamo a vivere e custodire la natura come dono di Dio<\/strong>, da rispettare e tramandare alle future generazioni\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN MARCO ARGENTANO (CS) &#8211; Il vescovo della Diocesi San Marco Argentano &#8211; Scalea, Stefano Rega, invia un messaggio di \u201cresponsabilit\u00e0 condivisa contro il flagello degli incendi\u201d. Monsignore di fronte al difficile periodo che il territorio calabrese sta vivendo per l&#8217;emergenza legata agli incendi boschivi, fa appello a tutti, indistintamente. &#8220;Dati recenti indicano che, dal [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":264517,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-264515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/264515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=264515"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/264515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/264517"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=264515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=264515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=264515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}