{"id":264696,"date":"2025-07-18T08:30:26","date_gmt":"2025-07-18T06:30:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=264696"},"modified":"2025-07-18T08:41:55","modified_gmt":"2025-07-18T06:41:55","slug":"acquappesa-diecimila-munizioni-sequestrate-si-allarga-linchiesta-sul-misterioso-studio-balistico","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/acquappesa-diecimila-munizioni-sequestrate-si-allarga-linchiesta-sul-misterioso-studio-balistico\/","title":{"rendered":"Acquappesa, diecimila munizioni sequestrate: si allarga l\u2019inchiesta sul misterioso studio balistico"},"content":{"rendered":"<p>ACQUAPPESA (CS) &#8211; Un vero e proprio caso quello del ritrovamento ad <strong><a href=\"https:\/\/quicosenza.it\/news\/tirreno\/armi-anche-guerra-rinvenute-ad-acquappesa-in-uno-studio-professionale\">Acquappesa<\/a><\/strong>, prima di decine di armi da fuoco, molte con matricola abrasa, e ora di un impressionante numero di munizioni: oltre <strong>10.000 proiettili<\/strong>, molte delle quali compatibili con armi da guerra, come il Kalashnikov, <strong>assieme a 20 caricatori militari<\/strong>. Si tratta del secondo sequestro, in pochi giorni, da parte dei finanzieri del Gico di Acquappesa. Materiale conservato in uno studio balistico che era di un noto perito, deceduto tre anni fa.<\/p>\n<p>E le attenzioni degli investigatori si sono concentrate sul fratello, che \u00e8 stato iscritto nel registro degli indagati. La Procura, guidata da Domenico Fiordalisi, non ha ancora emesso provvedimenti restrittivi, ma non esclude collegamenti con ambienti criminali. Le indagini, condotte nel massimo riserbo, proseguono serrate e nuovi sviluppi sono attesi nei prossimi giorni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACQUAPPESA (CS) &#8211; Un vero e proprio caso quello del ritrovamento ad Acquappesa, prima di decine di armi da fuoco, molte con matricola abrasa, e ora di un impressionante numero di munizioni: oltre 10.000 proiettili, molte delle quali compatibili con armi da guerra, come il Kalashnikov, assieme a 20 caricatori militari. Si tratta del secondo [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":231715,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-264696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/264696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=264696"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/264696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/231715"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=264696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=264696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=264696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}