{"id":26478,"date":"2013-10-09T11:52:16","date_gmt":"2013-10-09T09:52:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26478"},"modified":"2023-01-17T13:24:00","modified_gmt":"2023-01-17T12:24:00","slug":"10883-sila-sequestrato-un-bosco-all-interno-del-parco-nazionale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/10883-sila-sequestrato-un-bosco-all-interno-del-parco-nazionale\/","title":{"rendered":"Sila, sequestrato un bosco all&#8217;interno del Parco Nazionale"},"content":{"rendered":"<p><span style=\"font-size: 12px; line-height: 1;\">LONGOBUCCO \u2013 Pian piano era riuscito a far scomparire pi\u00f9 di 400 esemplari di pino e ontano.&nbsp;<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Un proprietario terriero residente a Longobucco \u00e8 stata denunciato per taglio abusivo di piante distruzione e danneggiamento di bellezze naturali e&nbsp;violazione alla legge quadro sulle aree protette. Tutto ci\u00f2 \u00e8 avvenuto a seguito di controlli&nbsp;effettuati dal Comando Stazione del Corpo Forestale dello Stato di Cava di Melis, dipendente dal&nbsp;Coordinamento Territoriale per l\u2019Ambiente della Sila, che ha accertato in localit\u00e0 \u201cCerviolo-Esco&nbsp;Serrato\u201d del comune di Longobucco (cs) un taglio abusivo di circa 400 piante. Si tratta di piante di&nbsp;\u201cPino Laricio\u201d e \u201cOntano\u201d tagliate dal proprietario del bosco, alcune delle quali ritrovate abbattute&nbsp;allo stato verde e lasciate sul letto di caduta per essere successivamente depezzate e trasportate.&nbsp;L\u2019area oggetto del taglio risulta essere sottoposta a vincolo idrogeologico e paesaggistico e ricade&nbsp;all\u2019interno della zona \u201c1\u201d del Parco della Sila, area questa dove \u00e8 vietato il taglio dei boschi,&nbsp;ad eccezione degli interventi necessari alla loro conservazione. Inoltre tale zona rientra in un&nbsp;pregevole comprensorio boscato nel quale il taglio irregolare effettuato ha interessato i migliori&nbsp;soggetti per valore economico e commerciale senza tener conto del danno arrecato al bosco ed&nbsp;all\u2019intero ecosistema. Il taglio abusivo \u00e8 avvenuto nonostante il proprietario avesse gi\u00e0 avuto&nbsp;il divieto al taglio da parte delle autorit\u00e0 preposte al rilascio delle autorizzazioni. A seguito del&nbsp;controllo, oltre al deferimento dell\u2019uomo si \u00e8 provveduto anche al sequestro penale dell\u2019intera area&nbsp;boscata estesa per circa 40 ettari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LONGOBUCCO \u2013 Pian piano era riuscito a far scomparire pi\u00f9 di 400 esemplari di pino e ontano.&nbsp;<\/p>\n","protected":false},"author":22,"featured_media":26479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-26478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26478"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26479"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}