{"id":265592,"date":"2025-07-26T18:30:14","date_gmt":"2025-07-26T16:30:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=265592"},"modified":"2025-07-26T18:09:30","modified_gmt":"2025-07-26T16:09:30","slug":"da-note-a-notte-di-fuoco-lappello-di-mara-cipolla-m5s-dopo-gli-incendi-a-belvedere-marittimo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/da-note-a-notte-di-fuoco-lappello-di-mara-cipolla-m5s-dopo-gli-incendi-a-belvedere-marittimo\/","title":{"rendered":"&#8220;Da Note\u2026 a Notte di Fuoco&#8221;: l&#8217;appello di Mara Cipolla (M5S) dopo gli incendi a Belvedere Marittimo"},"content":{"rendered":"<p>BELVEDERE MARITTIMO (CS) &#8211; Doveva essere una serata di festa e promozione turistica, ma le fiamme hanno cambiato tutto. Durante uno degli eventi estivi pi\u00f9 attesi a Belvedere Marittimo, il cielo si \u00e8 colorato, non di fuochi d\u2019artificio, ma di fumo e distruzione. A lanciare un accorato appello \u00e8 <strong>Mara Cipolla<\/strong>, Referente Giovani del Gruppo Territoriale del MoVimento 5 Stelle di Belvedere Marittimo (CS), che, <strong>dopo gli incendi divampati<\/strong> alle <strong>pendici del Monte La Caccia<\/strong>, ha voluto denunciare<strong> l\u2019assenza di programmazione e di interventi efficaci da parte del Governo regionale.<\/strong><\/p>\n<p>\u201cProprio durante uno degli eventi che pi\u00f9 di tutti caratterizzano le attivit\u00e0 turistiche estive, il Fuoco \u2013 incontrollato e distruttivo \u2013 stava distruggendo le nostre contrade, invece di illuminare il cielo per uno spettacolo di luci e colori\u201d. Un disastro che ha minacciato cittadini, ambiente e sicurezza pubblica, e che secondo la Cipolla evidenzia ancora una volta le <strong>lacune strutturali nella gestione dell\u2019emergenza<\/strong>. \u201cMi preme porre l\u2019attenzione sulla mancanza di pianificazione e collaborazione con le amministrazioni locali che il Governo Regionale dimostra quotidianamente \u2013 non solo in tema ambientale.\u201d<\/p>\n<p>Nel suo intervento, la referente 5 Stelle si \u00e8 rivolta anche al Sindaco e agli Assessori locali, affinch\u00e9 sfruttino la loro vicinanza politica con il Presidente della Regione e la Giunta, chiedendo interventi concreti: \u201cInvito il <strong>sindaco<\/strong> e gli <strong>assessori<\/strong> competenti a far s\u00ec che i bisogni e le necessit\u00e0 dei Comuni della Costa Tirrenica diventino finalmente temi di confronto serio tra Regione e territori\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BELVEDERE MARITTIMO (CS) &#8211; Doveva essere una serata di festa e promozione turistica, ma le fiamme hanno cambiato tutto. Durante uno degli eventi estivi pi\u00f9 attesi a Belvedere Marittimo, il cielo si \u00e8 colorato, non di fuochi d\u2019artificio, ma di fumo e distruzione. A lanciare un accorato appello \u00e8 Mara Cipolla, Referente Giovani del Gruppo [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":265593,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-265592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/265592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=265592"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/265592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/265593"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=265592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=265592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=265592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}