{"id":265596,"date":"2025-07-27T08:26:42","date_gmt":"2025-07-27T06:26:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=265596"},"modified":"2025-07-27T08:27:04","modified_gmt":"2025-07-27T06:27:04","slug":"rimborsopoli-a-rocca-di-neto-sospeso-il-sindaco-dattolo-decisione-ingiusta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rimborsopoli-a-rocca-di-neto-sospeso-il-sindaco-dattolo-decisione-ingiusta\/","title":{"rendered":"&#8216;Rimborsopoli&#8217;, a Rocca di Neto sospeso il sindaco Dattolo: \u00abDecisione ingiusta\u00bb"},"content":{"rendered":"<p>ROCCA DI NETO (KR) &#8211; Il<strong> sindaco di Rocca di Neto<\/strong>, in provincia di Crotone, <strong>Alfonso Dattolo<\/strong>, ex assessore regionale, a seguito della sentenza nell\u2019ambito del processo <strong>\u201c<a href=\"https:\/\/quicosenza.it\/news\/calabria\/rimborsopoli-sei-condanne-tra-gli-assolti-adamo-loiero-e-il-sindaco-di-rende-principe\" target=\"_blank\" rel=\"noopener\">Rimborsopoli<\/a>\u201d,<\/strong> che lo ha visto coinvolto insieme ad altri ex consiglieri regionali per il presunto <strong>utilizzo illecito dei fondi destinati ai gruppi consiliari <\/strong>e per il quale \u00e8 stato <strong>condannato a 4 anni e 8 mesi in primo grado<\/strong>, \u00e8 stato <strong>sospeso<\/strong> dal suo incarico.<\/p>\n<p>\u00c8 stata la Prefettura di Crotone a comunicare a Dattolo la <strong>sospensione per 18 mesi<\/strong> dalle sue funzioni di primo cittadino. Una decisione presa in linea con quanto prevede la legge Severino del 2012. Il Comune di Rocca di Neto, che Dattolo guidava dal 2020, verr\u00e0 amministrato fino alle prossime elezioni dalla vicesindaca<strong> Irene Dattolo.\u00a0<\/strong><\/p>\n<h3>&#8216;Rimborsopoli&#8217;, Dattolo vuole ricorrere in appello: &#8220;per difendere la dignit\u00e0 personale&#8221;<\/h3>\n<p>Il primo cittadino non l&#8217;ha presa bene e ha affidato il suo stato d&#8217;animo ed i suoi pensieri ad una lettera aperta indirizzata ai suoi concittadini pubblicata sui social. &#8220;Cari concittadini, ci sono scelte che si fanno con la mente e altre con il cuore. &#8211; scrive Dattolo &#8211; La mia decisione di restare a Rocca di Neto e guidarne l\u2019amministrazione nasce da entrambe: una <strong>scelta profonda e consapevole,<\/strong> rinnovata ogni giorno, anche nei momenti pi\u00f9 duri, come durante la pandemia, quando la responsabilit\u00e0 di proteggervi sembrava insostenibile&#8221;.<\/p>\n<p>&#8220;Ho sempre <strong>servito questa comunit\u00e0 con dedizione, rispetto e amore,<\/strong> anche in questo momento di grande <strong>tristezza e delusione<\/strong> mentre mi viene notificata la sospensione dalla carica di sindaco a seguito della condanna in primo grado nel processo &#8216;Rimborsopoli'&#8221;. aggiunge precisando la sua volont\u00e0 di ricorrere in appello contro la condanna &#8220;per<strong> difendere &#8211;<\/strong> afferma l&#8217;ex sindaco &#8211; la mia <strong>dignit\u00e0 personale<\/strong>&#8220;, pur ribadendo &#8220;il rispetto per la decisione del tribunale&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROCCA DI NETO (KR) &#8211; Il sindaco di Rocca di Neto, in provincia di Crotone, Alfonso Dattolo, ex assessore regionale, a seguito della sentenza nell\u2019ambito del processo \u201cRimborsopoli\u201d, che lo ha visto coinvolto insieme ad altri ex consiglieri regionali per il presunto utilizzo illecito dei fondi destinati ai gruppi consiliari e per il quale \u00e8 [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":265597,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-265596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/265596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=265596"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/265596\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/265597"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=265596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=265596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=265596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}