{"id":266064,"date":"2025-07-31T12:00:43","date_gmt":"2025-07-31T10:00:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=266064"},"modified":"2025-07-31T11:15:00","modified_gmt":"2025-07-31T09:15:00","slug":"non-poteva-avvicinarsi-ma-continuava-a-pedinare-la-sua-ex-arrestato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/non-poteva-avvicinarsi-ma-continuava-a-pedinare-la-sua-ex-arrestato\/","title":{"rendered":"Non poteva avvicinarsi ma continuava a pedinare la sua ex, arrestato"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; Era <strong>indagato per stalking<\/strong> ai danni della <strong>ex compagna,<\/strong> ha <strong>violato il\u00a0 provvedimento del divieto di avvicinamento<\/strong> ai luoghi frequentati dalla donna ed \u00e8 stato <strong>arrestato<\/strong>. I fatti sono avvenuti nel pomeriggio del 29 luglio 2025 quando gli agenti della Polizia di Stato in servizio alla Squadra Mobile di Vibo Valentia hanno accertato la violazione del provvedimento emesso dall\u2019Autorit\u00e0 Giudiziaria.<\/p>\n<p>L&#8217;ex compagna aveva denunciato l&#8217;uomo descrivendo i suoi <strong>comportamenti ossessivi e sistematici<\/strong> con\u00a0reiterate <strong>molestie<\/strong>: chiamate telefoniche insistenti sulla propria utenza telefonica, pedinamenti e <strong>appostamenti<\/strong> presso la sua <strong>abitazione<\/strong> e il luogo di <strong>lavoro<\/strong>. Una serie di comportamenti da creare nella donna un grave stato d\u2019ansia e di paura per l\u2019incolumit\u00e0 propria e dei suoi congiunti, costringendola ad alterare completamente le proprie abitudini di vita.<\/p>\n<h3>L&#8217;arresto e l&#8217;obbligo di lasciare il territorio di Vibo Valentia<\/h3>\n<p>Nonostante il provvedimento l&#8217;uomo \u00e8 stato colto <strong>transitare pi\u00f9 volte<\/strong> nei pressi del <strong>luogo di lavoro della vittima,<\/strong> comportamento reiterato che aveva fatto scattare il divieto d avvicinamento in un primo momento. Le condotte dell&#8217;uomo sono state documentate e ricostruite attraverso le <strong>immagini registrate dai sistemi di video sorveglianza<\/strong> presenti in zona che, sulla scorta delle modifiche apportate al codice di procedura penale dalle recenti innovazioni normative volte al <strong>contrasto della violenza sulle donne e della violenza domestica<\/strong>, hanno consentito agli agenti della Squadra Mobile di operare <strong>l\u2019arresto in flagranza differita<\/strong> dell\u2019autore del reato.<\/p>\n<p>L\u2019indagato, su disposizione del pm di turno, \u00e8 stato sottoposto agli <strong>arresti domiciliari<\/strong> presso la propria abitazione. Il questore della Provincia di Vibo Valentia ha emesso nei confronti dell\u2019uomo le misure di prevenzione del <strong>foglio di via obbligatorio<\/strong> con il quale \u00e8 stato obbligato allo stesso di <strong>lasciare il territorio del comune di Vibo Valentia<\/strong> e di <strong>non farvi ritorno per la durata di 3 anni. <\/strong>Nella mattinata di ieri, all\u2019esito dell\u2019udienza di convalida dell\u2019arresto, il gip presso il Tribunale di Vibo Valentia ha convalidato la misura precautelare applicando all\u2019uomo gli <strong>arresti domiciliari.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; Era indagato per stalking ai danni della ex compagna, ha violato il\u00a0 provvedimento del divieto di avvicinamento ai luoghi frequentati dalla donna ed \u00e8 stato arrestato. I fatti sono avvenuti nel pomeriggio del 29 luglio 2025 quando gli agenti della Polizia di Stato in servizio alla Squadra Mobile di Vibo Valentia hanno [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":266066,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-266064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/266064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=266064"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/266064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/266066"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=266064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=266064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=266064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}