{"id":26627,"date":"2013-10-16T03:58:57","date_gmt":"2013-10-16T01:58:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26627"},"modified":"2023-01-17T13:24:09","modified_gmt":"2023-01-17T12:24:09","slug":"10962-maltempo-in-arrivo-forti-temporali","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/10962-maltempo-in-arrivo-forti-temporali\/","title":{"rendered":"Maltempo, in arrivo forti temporali"},"content":{"rendered":"<p>COSENZA &#8211; In arrivo nelle prossime ore forti precipitazioni e venti intensi al sud.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La comunicazione arriva dal dipartimento della protezione civile, secondo una<strong> perturbazione proveniente dall&#8217;Atlantico<\/strong> attraversera&#8217; l&#8217;Italia e interesser\u00e0 in particolare le regioni centro-meridionali dove, oltre alle precipitazioni &#8211; localmente intense &#8211; si registrera&#8217; anche una intensificazione dei venti. Il dipartimento ha pertanto emesso un avviso di condizioni meteo avverse che &#8220;prevede precipitazioni anche a carattere di rovescio o temporale su Lazio ed in successiva estensione anche a Basilicata, <strong>Calabria<\/strong>, Sicilia e Puglia&#8221;. &#8211; &#8220;I fenomeni potranno dare luogo a rovesci di forte intensita&#8217;, locali grandinate, frequente attivita&#8217; elettrica e forti raffiche di vento&#8221;. Per la giornata di oggi si prevedono venti nord occidentali da forti a burrasca sulle due isole maggiori e sulla Calabria, in estensione anche a Basilicata e Puglia&#8221;. Per quanto concerne <strong>Cosenza<\/strong>, previsto cielo coperto e temporali con una temperatura massima che si attester\u00e0 intorno ai 19\u00b0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; In arrivo nelle prossime ore forti precipitazioni e venti intensi al sud.<\/p>\n","protected":false},"author":19,"featured_media":26628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-26627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26627"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26627\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26628"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}