{"id":26711,"date":"2013-10-19T05:41:58","date_gmt":"2013-10-19T03:41:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26711"},"modified":"2023-01-17T13:24:14","modified_gmt":"2023-01-17T12:24:14","slug":"11005-condannato-in-appello-il-branco-che-stupro-anna-maria-scarfo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11005-condannato-in-appello-il-branco-che-stupro-anna-maria-scarfo\/","title":{"rendered":"Condannato in appello il &#8220;branco&#8221; che stupr\u00f2 Anna Maria Scarf\u00f2"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; La Corte d&#8217;appello ha ridotto le condanne per i cinque imputati, accusati di aver stuprato Anna Maria Scarf\u00f2.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La giovane, di San Martino di Taurianova, quando aveva 13 anni, era stata violentata dal branco. Oggi \u00e8 costretta a vivere in una localit\u00e0 protetta dopo aver denunciato i suoi aguzzini che sono stati condannati: 7 anni di reclusione per Maurizio Hanaman, Giuseppe Chirico, Antonio Cianci e Antonio Cutrupi; Fabio Piccolo invece, \u00e8 stato condannato a 7 anni e 8 mesi. La lettura del dispositivo \u00e8 stata ascoltata in religioso silenzio e nonostante le condanne siano state ridotte, la vittima del branco, pu\u00f2 forse iniziare a percorrere una nuova strada per dimenticare quell\u2019incubo, quei ragazzi che la picchiarono e violentarono quando aveva solo 13 anni e che lo avrebbe fatto per anni. Una ragazza che non ha trovato il sostegno di nessuno, n\u00e9 della sua comunit\u00e0 n\u00e9 del parroco Don Antonio Scordo che invece avrebbe dovuto accogliere il suo grido di dolore e che verr\u00e0 condannato per falsa testimonianza. Dopo 10 anni si chiude questo capitolo con la condanna in appello di quei giovani \u201cmostri\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; La Corte d&#8217;appello ha ridotto le condanne per i cinque imputati, accusati di aver stuprato Anna Maria Scarf\u00f2.<\/p>\n","protected":false},"author":19,"featured_media":26712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-26711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26711"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26712"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}