{"id":26713,"date":"2013-10-20T05:18:38","date_gmt":"2013-10-20T03:18:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26713"},"modified":"2023-01-17T13:24:14","modified_gmt":"2023-01-17T12:24:14","slug":"11006-due-calabresi-in-corsa-per-miss-italia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11006-due-calabresi-in-corsa-per-miss-italia\/","title":{"rendered":"Due calabresi in corsa per Miss Italia"},"content":{"rendered":"<p>JESOLO (VE) &#8211; Si chiamano Alessia Siclari e Graziella Cilione: segni particolari \u201cbelle\u201d.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Saranno loro a rappresentare la bellezza calabrese al Teatro Vivaldi di Jesolo: Graziella Cilione, Miss Eleganza Calabria in gara con il numero 161 e Alessia Siclari, Miss Calabria in carica, diciottenne, capelli neri, occhi castani, di Taurianova, alta 1.75. La finalissima \u00e8 prevista per domenica prossima 27 ottobre e a darsi battaglia a suon di curve, sorrisi ma anche cultura e personalit\u00e0, sessantatre finaliste, ovviamente tutte italiane. Abbandonato lo schermo Rai, la diretta tv sar\u00e0 in prima serata sull\u2019emittente privata \u201cLa7\u201d; a condurre la finale della kermesse saranno l\u2019attore Massimo Ghini, Cesare Bocci e Francesca Chillemi (Miss Italia nel 2003 e attrice nascente nel panorama cinematografico italiano).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JESOLO (VE) &#8211; Si chiamano Alessia Siclari e Graziella Cilione: segni particolari \u201cbelle\u201d.<\/p>\n","protected":false},"author":19,"featured_media":26714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-26713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26713"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26714"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}