{"id":267245,"date":"2025-08-12T13:10:43","date_gmt":"2025-08-12T11:10:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=267245"},"modified":"2025-08-12T13:11:30","modified_gmt":"2025-08-12T11:11:30","slug":"insulti-e-auguri-di-malattia-a-wanda-ferro-e-giorgia-meloni-al-limite-dellincivilta-e-dello-squallore","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/insulti-e-auguri-di-malattia-a-wanda-ferro-e-giorgia-meloni-al-limite-dellincivilta-e-dello-squallore\/","title":{"rendered":"Insulti e auguri di malattia a Wanda Ferro e Giorgia Meloni: \u00abAl limite dell&#8217;incivilt\u00e0 e dello squallore\u00bb"},"content":{"rendered":"<p>CATANZARO &#8211; <strong>Insulti<\/strong> e <strong>l&#8217;augurio di contrarre una malattia.<\/strong> Queste le parole che sono state rivolte sui social network sia alla presidente del Consiglio <strong>Giorgia Meloni<\/strong> che al sottosegretario all&#8217;Interno e deputata di Fratelli d&#8217;Italia <strong>Wanda Ferro<\/strong>, &#8220;colpevole&#8221; di aver fatto un post a favore della premier. La deputata calabrese ha fatto sapere di aver <strong>sporto gi\u00e0 denuncia.\u00a0<\/strong><\/p>\n<p>&#8220;Avevo fatto un post pro Giorgia Meloni &#8211; spiega Ferro &#8211; e poi alcune persone mi hanno segnalato una serie di <strong>commenti con insulti e l&#8217;auguri di contrarre una malattia<\/strong>&#8220;. Quando il linguaggio arriva a &#8220;questi livelli vuol dire che si offende anche quanti soffrono perch\u00e8 malati di cancro. &#8211; ha aggiunto &#8211; <strong>Siamo al limite dell&#8217;incivilt\u00e0 e dello squallore<\/strong>&#8220;.<\/p>\n<h3>Occhiuto e la solidariet\u00e0 a Ferro e Meloni: &#8220;Attacchi vergognosi&#8221;<\/h3>\n<p>\u201dAugurare il male, nascondendosi dietro l\u2019anonimato della rete, \u00e8 un gesto da vigliacchi e incivili. Esprimo la mia<strong> piena vicinanza<\/strong> al sottosegretario di Stato Wanda Ferro, bersaglio di<strong> un\u2019aggressione vile e ingiustificabile sui social,<\/strong> dopo un post dedicato alla presidente del Consiglio, Giorgia Meloni, alla quale va ugualmente tutta la mia solidariet\u00e0 per essere ancora una volta nel mirino di odiatori indegni di vivere in una comunit\u00e0 democratica. Riferimenti a malattie o, peggio, alla morte, non hanno nulla a che vedere con il legittimo confronto politico. Sono comportamenti che hanno un solo nome: <strong>attacchi vergognosi&#8221;.\u00a0 <\/strong>Cos\u00ec Roberto Occhiuto si \u00e8 espresso in merito agli attacchi ricevuti da Wanda Ferro sui social.<\/p>\n<h3>La Polizia al fianco di Wanda Ferro: &#8220;Gesto ignobile&#8221;<\/h3>\n<p>&#8220;Esprimiamo la nostra pi\u00f9 sincera e convinta solidariet\u00e0 e vicinanza all&#8217;onorevole Wanda Ferro, sottosegretario di Stato al Ministero dell&#8217;Interno, vittima di un attacco vile e vergognoso sui social network, culminato con l&#8217;augurio di una gravissima malattia.<strong> Un gesto ignobile<\/strong> che condanniamo con fermezza e che, giustamente, \u00e8 stato denunciato&#8221;. \u00c8 quantro hanno detto <strong>Franco Maccari,<\/strong> vice presidente nazionale, e <strong>Giuseppe Brugnano,<\/strong> segretario nazionale del sindacato Fsp Polizia di Stato.<\/p>\n<p>&#8220;Chi si nasconde dietro l&#8217;anonimato della rete per diffondere odio, violenza e disprezzo &#8211; aggiungono Maccari e Brugnano &#8211; non rappresenta altro che la feccia della societ\u00e0. \u00c8 indispensabile riaffermare con forza che il <strong>confronto politico e pubblico,<\/strong> anche quando acceso, <strong>non pu\u00f2 mai degenerare in aggressioni verbali o auguri di morte,<\/strong> che attentano ai principi fondamentali della convivenza civile e democratica&#8221;.<\/p>\n<p>&#8220;Al Sottosegretario Ferro rinnoviamo non solo la nostra vicinanza personale e istituzionale, ma anche il<strong> ringraziamento per il coraggio e la determinazione<\/strong> con cui ha scelto di denunciare pubblicamente questo episodio. Il suo gesto rappresenta un <strong>esempio da seguire:<\/strong> l&#8217;odio in rete non pu\u00f2 e non deve trovare spazio in una societ\u00e0 che si definisce civile. \u00c8 giunto il momento &#8211; concludono &#8211; che chi si rende responsabile di simili atti venga chiamato a risponderne nelle sedi opportune, senza alcuna tolleranza&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Insulti e l&#8217;augurio di contrarre una malattia. Queste le parole che sono state rivolte sui social network sia alla presidente del Consiglio Giorgia Meloni che al sottosegretario all&#8217;Interno e deputata di Fratelli d&#8217;Italia Wanda Ferro, &#8220;colpevole&#8221; di aver fatto un post a favore della premier. La deputata calabrese ha fatto sapere di aver [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":267248,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-267245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/267245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=267245"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/267245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/267248"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=267245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=267245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=267245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}