{"id":26763,"date":"2013-10-21T05:34:21","date_gmt":"2013-10-21T03:34:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26763"},"modified":"2023-01-17T13:24:17","modified_gmt":"2023-01-17T12:24:17","slug":"11031-il-comune-di-cosenza-sostiene-il-teatro-dell-acquario","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11031-il-comune-di-cosenza-sostiene-il-teatro-dell-acquario\/","title":{"rendered":"Il Comune di Cosenza sostiene il teatro dell\u2019Acquario"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\">COSENZA &#8211; \u201cNon possiamo consentire che un presidio culturale simbolo di innovazione e di sperimentalismo nel campo dell\u2019arte scenica, qual \u00e8 il teatro dell\u2019Acquario, scompaia dal panorama della nostra citt\u00e0\u201d.<\/p>\n<p>  <!--more-->  <\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Queste le parole del sindaco Mario Occhiuto, relativamente allo sfratto esecutivo che riguarda i locali in cui ha sede il prestigioso Centro Rat. \u201cIn anni di offerte di cartelloni contemporanei e di formazione per tanti appassionati che hanno trovato in Antonello Antonante un punto di riferimento importante, il teatro dell\u2019Acquario \u00e8 entrato a far parte della storia di Cosenza. Pur trattandosi di una struttura privata \u2013 aggiunge Occhiuto \u2013 l\u2019Amministrazione comunale non pu\u00f2 restare inerme di fronte al rischio di una chiusura definitiva. Venerd\u00ec scorso l\u2019assessore alla Cultura Geppino De Rose ha voluto portare personalmente il sostegno della casa municipale partecipando a un\u2019assemblea pubblica per vagliare eventuali soluzioni. Ma non ci fermeremo qui \u2013 conclude il primo cittadino \u2013 Nei prossimi giorni attueremo le iniziative necessarie affinch\u00e9 uno dei patrimoni culturali della comunit\u00e0 cittadina e regionale non venga spento inesorabilmente a causa della crisi economico-finanziaria\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; \u201cNon possiamo consentire che un presidio culturale simbolo di innovazione e di sperimentalismo nel campo dell\u2019arte scenica, qual \u00e8 il teatro dell\u2019Acquario, scompaia dal panorama della nostra citt\u00e0\u201d.<\/p>\n","protected":false},"author":19,"featured_media":26764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-26763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26763"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26764"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}