{"id":26769,"date":"2013-10-21T06:07:37","date_gmt":"2013-10-21T04:07:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26769"},"modified":"2023-01-17T13:24:17","modified_gmt":"2023-01-17T12:24:17","slug":"11034-il-ministro-carrozza-oggi-all-unical-polemiche-del-m5s","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11034-il-ministro-carrozza-oggi-all-unical-polemiche-del-m5s\/","title":{"rendered":"Il ministro Carrozza oggi all&#8217;Unical, polemiche del M5S"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\">RENDE &#8211; Il ministro Maria Chiara Carroza, sar\u00e0 questa sera alle 19.30 all&#8217;Universit\u00e0 della Calabria per inaugurare il nuovo complesso residenziale San Gennaro, situato nei pressi del vecchio polifunzionale.<\/p>\n<p>  <!--more-->  <\/p>\n<p class=\"p1\" style=\"text-align: justify;\">In merito alla sua visita istituzionale \u00e8 intervenuto il Movimento 5 stelle che avrebbe intenzione di &#8220;rovinare la festa&#8221;. Infatti \u00e8 intervenuto il grillino Molinari: &#8220;A fine luglio ho presentato, al Senato, un\u2019interrogazione diretta ad avere ragguagli dal Ministro dell\u2019Istruzione, dell\u2019Universit\u00e0 e della Ricerca, per quanto concerne l\u2019Universit\u00e0 della Calabria, sull\u2019inadeguata applicazione della normativa sulla trasparenza &#8211; di cui al D.Lgs 150\/09 &#8211; sia in termini di&nbsp; accessibilit\u00e0 che di informazioni pubblicate (soprattutto rispetto agli incarichi esterni dei docenti e alle attivit\u00e0 gestionali relative a servizi, lavori, appalti), derivando da ci\u00f2 l\u2019impossibilit\u00e0 di trovare sul sito UNICAL i verbali specifici dei vari organi collegiali. Ancora non ho ricevuto risposta dall\u2019esponente del partito unico, il cui Governo&nbsp;\u00e8 normalmente&nbsp;impegnato in quella decretazione d\u2019urgenza decisa in sede diversa da quella parlamentare, trasformata in un bivacco di inconfessabili interessi.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Tuttavia, ho avuto notizia che il Ministro Carrozza dedicher\u00e0 parte del suo prezioso tempo all\u2019inaugurazione, il prossimo 21 ottobre, del nuovo complesso residenziale San Gennaro (nei pressi del vecchio Polifunzionale): sono felice di sapere che non \u00e8 insensibile alle sorti della nostra Universit\u00e0. Sembra, peraltro, che si tratti di una delle solite inaugurazioni di facciata delle quali la Calabria dovrebbe detenere un non invidiabile record, visto che si tratta di un\u2019opera non terminata e che &#8211; nella migliore delle ipotesi &#8211; andrebbe a regime la prossima primavera : una delle tante beffe per gli studenti che si aspettano di vivere in un Paese che onori e rispetti il diritto allo studio dei suoi giovani. Si tratter\u00e0, allora, di un modo in cui certi personaggi, che fanno della gestione delle istituzioni una monarchia &#8211; vista la durata della loro carica &#8211; poco illuminata, vogliono far ricordare che non si accomiateranno mai da quegli scranni che hanno occupato: un ricordo che hanno concretamente lasciato, autonominandosi amministratori delle societ\u00e0 partecipate dall&#8217;Universit\u00e0, vero ex-Rettore La Torre? Un avvenimento ufficiale, insomma, e per inviti (con contorno di partecipazione delle autorit\u00e0 civili, militari e religiose), che loro sono sempre l\u00ec. Nulla di nuovo sotto lo stellone italico riscaldato dal sole clientelistico del Mezzogiorno: altro che legalit\u00e0 e diritto allo studio! Mi dispiace di non poter essere sul Ponte Bucci quando luned\u00ec prossimo sua Eccellenza transiter\u00e0 in visita guidata; sar\u00f2 in visita, a costo zero per il Paese, a Bruxelles, ospite della Commissione europea sia il 21 che il 22 ottobre, occasione nella quale il Presidente del Senato ha sottolineato la gratuit\u00e0 della missione, facendomi capire che dovr\u00f2 autonomamente provvedere al vitto in questi due giorni.&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">&nbsp;<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Chiss\u00e0 se la spending review interesser\u00e0 anche la cerimonia d&#8217;inaugurazione : voglio sperare che non venga messo a carico dell\u2019Universit\u00e0 della Calabria un eventuale rinfresco (che sarebbe pure un po\u2019 scortese visto che sarebbe per pochi e non per tutti). Terremo, comunque, alta la guardia per scongiurare&nbsp;un ulteriore seguito di quei circoli pseudo scientifico-culturali di spartizioni occulte di consulenze per progetti di mera fantasia destinati a rimanere sulla carta, al contrario dei vantaggi concreti che danno ai loro artefici. Non so se il nome benaugurale del complesso permetter\u00e0&nbsp;agli studenti di ottenere i loro sospirati alloggi entro la prossima primavera ; so che&nbsp;non ci saranno santi sufficienti a garantire che questi personaggi, che non vogliono andarsene, possano continuare ad operare nella moltiplicazione &#8211; assai poco miracolosa &#8211; degli incarichi&#8221;.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Il ministro Maria Chiara Carroza, sar\u00e0 questa sera alle 19.30 all&#8217;Universit\u00e0 della Calabria per inaugurare il nuovo complesso residenziale San Gennaro, situato nei pressi del vecchio polifunzionale.<\/p>\n","protected":false},"author":19,"featured_media":26770,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,7],"tags":[],"class_list":["post-26769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26769"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26770"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}