{"id":26781,"date":"2013-10-21T08:46:21","date_gmt":"2013-10-21T06:46:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26781"},"modified":"2023-01-17T13:24:18","modified_gmt":"2023-01-17T12:24:18","slug":"11040-tragedia-in-sila-recuperato-il-velivolo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11040-tragedia-in-sila-recuperato-il-velivolo\/","title":{"rendered":"Tragedia in Sila, recuperato il velivolo"},"content":{"rendered":"<p>COTRONEI (KR) &#8211; E&#8217; stato recuperato nella tarda mattinata di oggi dai Vigili del Fuoco l&#8217;aereo da turismo inabissatosi ieri nelle acque del lago Ampollino.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il velivolo biposto sar\u00e0 ora trasferito in un <strong>deposito giudiziario<\/strong> a disposizione della magistratura che ha avviato un&#8217;inchiesta per accertare le cause dell&#8217;incidente nel quale ha perso la vita uno dei due occupanti. Il corpo della vittima,<strong> Egidio Ritacca, 44enne veterinario di Firmo (Cs)<\/strong>, \u00e8 stato recuperato ieri sera dai Vigili del fuoco. Il cadavere era adagiato sul fondo del lago a circa 4 metri di profondita&#8217;. Dai primi rilievi medici la morte di Ritacca sarebbe da attribuire ad annegamento, ma sar\u00e0 <strong>l&#8217;autopsia<\/strong> disposta dalla Procura della Repubblica di Crotone a stabilire le cause precise del decesso. Il pilota del Piper, <strong>Pier Giorgio Falvo, 52enne di Montalto Uffugo (Cs)<\/strong>, che ha effettuato un ammaraggio una volta resosi conto di un&#8217;avaria al motore, \u00e8 riuscito a raggiungere la riva, tentando invano di trascinare anche il compagno in difficolt\u00e0 ma la stanchezza, l&#8217;acqua fredda e i vestiti che lo appesantivano lo hanno costretto a lasciare la presa. Vano anche il tentativo del pilota di un altro ultraleggero di prestare soccorso ai colleghi in difficolt\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COTRONEI (KR) &#8211; E&#8217; stato recuperato nella tarda mattinata di oggi dai Vigili del Fuoco l&#8217;aereo da turismo inabissatosi ieri nelle acque del lago Ampollino.<\/p>\n","protected":false},"author":19,"featured_media":26782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-26781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26781"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26782"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}