{"id":267889,"date":"2025-08-20T15:55:23","date_gmt":"2025-08-20T13:55:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=267889"},"modified":"2025-08-20T15:55:23","modified_gmt":"2025-08-20T13:55:23","slug":"regionali-lucano-pasquale-tridico-e-una-speranza-volto-pulito-per-la-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/regionali-lucano-pasquale-tridico-e-una-speranza-volto-pulito-per-la-calabria\/","title":{"rendered":"Regionali, Lucano: \u00abPasquale Tridico \u00e8 una speranza, volto pulito per la Calabria\u00bb"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; &#8220;<strong>Pasquale Tridico \u00e8 una speranza per la Calabria.<\/strong> L&#8217;ho sentito poco fa e mi ha detto &#8216;Mimmo ci sono, ci sono'&#8221;. Lo ha detto all&#8217;ANSA <strong>l&#8217;europarlamentare di Avs e sindaco di Riace, Mimmo Lucano<\/strong>.<\/p>\n<p>&#8220;Ho avuto la fortuna di conoscere Tridico a Bruxelles &#8211; ha aggiunto Lucano &#8211; e posso dire che \u00e9 una persona che ha dimostrato con i fatti il suo valore con il reddito di cittadinanza e con la sua <strong>attenzione particolare per le categorie sociali pi\u00f9 vulnerabili, pi\u00f9 deboli<\/strong> e per le aree interne come Riace.<\/p>\n<p>Credo che attorno a Pasquale Tridico tutta la sinistra si riconoscer\u00e0, grazie alla politica che lui ha messo in atto. <strong>Pasquale Tridico \u00e8 il volto pulito della Calabria<\/strong>. Il mio appello \u00e8 a tutto il popolo che si riconosce in questi valori. Ma \u00e8 anche a tutto il centrosinistra per dare una risposta vera e una speranza per la Calabria. Le divisioni non servono a nessuno. Il nostro obiettivo deve essere battere le destre e ricostruire la Regione, dimostrando che un&#8217;altra Calabria \u00e8 possibile&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; &#8220;Pasquale Tridico \u00e8 una speranza per la Calabria. L&#8217;ho sentito poco fa e mi ha detto &#8216;Mimmo ci sono, ci sono&#8217;&#8221;. Lo ha detto all&#8217;ANSA l&#8217;europarlamentare di Avs e sindaco di Riace, Mimmo Lucano. &#8220;Ho avuto la fortuna di conoscere Tridico a Bruxelles &#8211; ha aggiunto Lucano &#8211; e posso dire che [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":267892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-267889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/267889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=267889"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/267889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/267892"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=267889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=267889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=267889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}