{"id":26793,"date":"2013-10-22T05:01:54","date_gmt":"2013-10-22T03:01:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26793"},"modified":"2023-01-17T13:24:19","modified_gmt":"2023-01-17T12:24:19","slug":"11046-barile-sull-ammanco-nelle-casse-della-field-voglio-restituire-tutto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11046-barile-sull-ammanco-nelle-casse-della-field-voglio-restituire-tutto\/","title":{"rendered":"Barile sull&#8217;ammanco nelle casse della Field: &#8220;voglio restituire tutto&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Ammetto gli addebiti precisando che nel corso delle indagini abbiamo chiesto per tre volte di rendere dichiarazioni confessorie&#8221;.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Domenico Barile, ex presidente della Field (Fondazione innovazione emersione locale disegno del territorio), Ente in house della Regione Calabria, ha voluto sottolineare la sua volont\u00e0 di <strong>restituire quanto indebitamente percepito<\/strong>: &#8220;Ribadisco la volont\u00e0 del risarcimento del danno nel piu&#8217; breve tempo possibile che mi sar\u00e0 dato. Mi riservo di fornire ulteriori chiarimenti al pm titolare delle indagini&#8221;. Queste le uniche e poche parole di Barile nel corso dell&#8217;<strong>interrogatorio di garanzia<\/strong>, raggiunto nei giorni scorsi da un provvedimento di custodia cautelare agli arresti domiciliari nell&#8217;ambito dell&#8217;inchiesta della Procura della Repubblica di Catanzaro su un ammanco patrimoniale di <strong>500 mila euro dalle casse della fondazione<\/strong>. Barile, comparso davanti al giudice per le indagini preliminari di Cosenza che lo ha sentito per rogatoria, affiancato dal suo legale, Roberto Le Pera (codifensore con Giancarlo Pittelli), si e&#8217; avvalso della facolta&#8217; di non rispondere, rendendo solo dichiarazioni spontanee. Piuttosto ha manifestato l&#8217;intenzione di parlare davanti al pubblico ministero di Catanzaro, Paolo Petrolo, titolare delle indagini che lo hanno coinvolto.<\/p>\n<p>&nbsp;<\/p>\n<p>Le indagini, condotte dagli uomini della Guardia di finanza, sono partite lo scorso dicembre da un dettagliato esposto presentato dal revisore dei conti della Field, cui segui&#8217; l&#8217;immediata decisione della Giunta regionale calabrese di sospendere Barile dall&#8217;incarico presso l&#8217;Ente. Gli investigatori partirono subito con gli accertamenti necessari a verificare i movimenti di denaro avvenuti sul conto corrente della Fondazione, per identificare chi vi aveva accesso e chi, materialmente, dispose dei soldi. A met\u00e0 gennaio l&#8217;attenzione dei finanzieri e del sostituto Petrolo era gia&#8217; concentrata su alcuni assegni circolari di diverso importo ed emessi per destinatari diversi, che i militari della Guardia di finanza hanno ritrovato presso diverse banche, tutti sottoscritti da Barile che, per parte sua, fin dall&#8217;avvio dell&#8217;inchiesta aveva chiesto di poter essere sentito dagli inquirenti. <strong>Cinquantuno<\/strong>, alla fine, gli <strong>assegni circolari<\/strong> &#8220;incriminati&#8221; con i quali Barile, secondo quanto ricostruito dettagliatamente dalle Fiamme gialle, uso&#8217; i fondi della Field &#8220;a beneficio proprio e di soggetti allo stesso legati da rapporti personali ed economico finanziari e, comunque, per soddisfare esclusivamente proprie esigenze private&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Ammetto gli addebiti precisando che nel corso delle indagini abbiamo chiesto per tre volte di rendere dichiarazioni confessorie&#8221;.<\/p>\n","protected":false},"author":19,"featured_media":26794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-26793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26793"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26794"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}