{"id":268003,"date":"2025-08-23T18:30:39","date_gmt":"2025-08-23T16:30:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=268003"},"modified":"2025-08-23T16:39:49","modified_gmt":"2025-08-23T14:39:49","slug":"taste-experience-calabria-da-spilinga-a-cosenza-viaggio-nei-sapori-autentici-a-km-0","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/taste-experience-calabria-da-spilinga-a-cosenza-viaggio-nei-sapori-autentici-a-km-0\/","title":{"rendered":"Taste Experience Calabria: da Spilinga a Cosenza, viaggio nei sapori autentici a Km 0"},"content":{"rendered":"<div dir=\"auto\">COSENZA &#8211; Prende il via &#8220;Taste Experience Calabria&#8221;, un progetto itinerante che da agosto a settembre 2025 animer\u00e0 cinque comuni calabresi \u2013 <strong>Spilinga, Lago, Nicotera, Tropea e Cosenza<\/strong> \u2013 per promuovere la ricchezza enogastronomica e culturale dei territori calabresi. L&#8217;iniziativa,<strong> &#8220;Viaggio nella Calabria a Km 0&#8221;<\/strong>, offre un&#8217;esperienza immersiva che punta a valorizzare i prodotti tipici e a sensibilizzare il pubblico sull&#8217;importanza della dieta mediterranea e di un&#8217;alimentazione sana e sostenibile. <strong>Il progetto si articola in cinque giornate<\/strong> ricche di eventi, tra cui laboratori sensoriali, degustazioni e visite aziendali. L&#8217;obiettivo \u00e8 duplice: far conoscere le eccellenze calabresi ed educare a un consumo consapevole, riducendo l&#8217;impatto ambientale.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">\u00abTaste Experience Calabria nasce dall&#8217;esigenza di offrire un&#8217;esperienza autentica del territorio, permettendo ai partecipanti di vivere la Calabria attraverso i suoi sapori ed i suoi valori\u00bb, spiega Corrado Rossi, presidente dell&#8217;Associazione Km0. Le azioni chiave del progetto:<strong> Gemellaggi gastronomici<\/strong>: L&#8217;iniziativa unisce idealmente due comunit\u00e0, Spilinga (patria della &#8216;nduja) e Lago (nota per la soppressata artigianale), in un percorso di collaborazione. Durante gli eventi gli chef uniranno le due eccellenze in una pietanza originale, a testimonianza del legame tra tradizione e innovazione.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><strong>Tavolata nel Borgo<\/strong>: Un momento di convivialit\u00e0 che trasforma piazze e centri storici in grandi feste, dove cittadini e visitatori potranno degustare piatti della tradizione realizzati con prodotti a Km 0, accompagnati da musica e racconti, per riscoprire il valore sociale del cibo.<\/div>\n<div dir=\"auto\"><\/div>\n<h3 dir=\"auto\">Le prime due tappe all&#8217;insegna dei gemellaggi gastronomici<\/h3>\n<div dir=\"auto\">Il viaggio inizia il 25 agosto 2025 a Lago (CS) e prosegue il giorno seguente, 26 agosto 2025 a Spilinga (VV). Queste prime due tappe saranno caratterizzate da un vero e proprio gemellaggio gastronomico tra i due comuni, noti rispettivamente per la soppressata artigianale e la &#8216;nduja. Per celebrare questo legame, l&#8217;Accademia Internazionale di Cucina Mediterranea creer\u00e0 una pietanza unica, che unir\u00e0 sapientemente le due eccellenze locali, esaltando l&#8217;identit\u00e0 e la tradizione di entrambi i territori.<\/div>\n<div dir=\"auto\"><\/div>\n<h3 dir=\"auto\">25 Agosto 2025: &#8220;Taste Experience LAGO: Degustando il Borgo&#8221;<\/h3>\n<div dir=\"auto\">La giornata a Lago inizia alle 11:00 con visite e degustazioni della <strong>Soppressata di Lago<\/strong>. Alle 18:30, un incontro sull&#8217;argomento sar\u00e0 ospitato presso l&#8217;Auditorium del Comune. Il percorso prosegue alle 19:30 con una Wine Taste Experience e alle 20:30 con la &#8220;Tavolata nel Borgo&#8221; in localit\u00e0 Laghitello. Qui si terr\u00e0 un gemellaggio gastronomico, con una pietanza che unisce la soppressata di Lago e la &#8216;nduja di Spilinga, accompagnato dai prodotti del <strong>Gal STS Savuto, Tirreno, Serre Cosentine<\/strong> ed animata da musica di tradizione popolare. In questa giornata si celebra il gemellaggio gastronomico tra Lago e Spilinga alla presenza di Enzo Sganga, sindaco di Lago, Enzo Marasco Sindaco di Spilinga e Luigi Provenzano presidente Gal- STS &#8211; Savuto -Tirreno &#8211; Serre Cosentine.<\/div>\n<div dir=\"auto\"><\/div>\n<h3 dir=\"auto\">26 Agosto 2025: &#8220;Taste Experience SPILINGA: Degustando il Borgo&#8221;<\/h3>\n<div dir=\"auto\">La seconda tappa a Spilinga avr\u00e0 inizio alle 11:00 con visite e degustazioni della &#8216;Nduja. Seguir\u00e0 un incontro con esperti, chef ed una Wine Taste Experience. La giornata si concluder\u00e0 alle 20:30 con la &#8220;Tavolata nel Borgo&#8221;, presso Piazza Ferdinando Pontoriero, che proporr\u00e0 nuovamente il gemellaggio gastronomico, con prodotti del Gal Terre Vibonesi e musica tradizionale.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">La manifestazione \u00e8 stata finanziata dal Ministero dell&#8217;agricoltura, della Sovranit\u00e0 alimentare e delle Foreste a seguito dell&#8217;Avviso contributi per iniziative di rilievo locale, regionale e interregionale rivolte ad azioni di valorizzazione nel settore agricolo e agroalimentare, anno 2025. Per maggiori informazioni e per conoscere il calendario completo degli eventi, \u00e8 possibile visitare il canale social del progetto.<\/div>\n<div dir=\"auto\"><a href=\"https:\/\/www.facebook.com\/tasteexperiencecalabria\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/tasteexperiencecalabria\/<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Prende il via &#8220;Taste Experience Calabria&#8221;, un progetto itinerante che da agosto a settembre 2025 animer\u00e0 cinque comuni calabresi \u2013 Spilinga, Lago, Nicotera, Tropea e Cosenza \u2013 per promuovere la ricchezza enogastronomica e culturale dei territori calabresi. L&#8217;iniziativa, &#8220;Viaggio nella Calabria a Km 0&#8221;, offre un&#8217;esperienza immersiva che punta a valorizzare i prodotti [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":225016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-268003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=268003"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/225016"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=268003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=268003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=268003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}