{"id":268191,"date":"2025-08-24T22:28:21","date_gmt":"2025-08-24T20:28:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=268191"},"modified":"2025-08-24T22:28:21","modified_gmt":"2025-08-24T20:28:21","slug":"incendio-al-sesto-piano-di-un-appartamento-intervento-lampo-dei-pompieri-evita-il-peggio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/incendio-al-sesto-piano-di-un-appartamento-intervento-lampo-dei-pompieri-evita-il-peggio\/","title":{"rendered":"Incendio al sesto piano di un appartamento: intervento lampo dei pompieri evita il peggio"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Sono durate oltre un&#8217;ora le operazioni di spegnimento di<strong> un incendio divampato all&#8217;interno di un appartamento<\/strong> di uno stabile del rione Arghill\u00e0, a Reggio Calabria. Le tre squadre dei Vigili del fuoco, due provenienti dalla sede di Via Europa e una da Villa San Giovanni sono riuscite, con il supporto dell&#8217;autoscala, ad accedere dal balcone dell&#8217;immobile sito al sesto piano fuori terra. In poco tempo<strong> i pompieri hanno domato l&#8217;incendio localizzato in cucina<\/strong> e messo in sicurezza l&#8217;immobile, oramai pesantemente danneggiato dal calore e dalla fuliggine. Il tempestivo intervento ha evitato che le fiamme si propagassero agli altri locali attigui. Le cause dell&#8217;incendio sono in corso di accertamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Sono durate oltre un&#8217;ora le operazioni di spegnimento di un incendio divampato all&#8217;interno di un appartamento di uno stabile del rione Arghill\u00e0, a Reggio Calabria. Le tre squadre dei Vigili del fuoco, due provenienti dalla sede di Via Europa e una da Villa San Giovanni sono riuscite, con il supporto dell&#8217;autoscala, ad [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":268192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-268191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=268191"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268191\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/268192"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=268191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=268191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=268191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}