{"id":268207,"date":"2025-08-25T11:30:59","date_gmt":"2025-08-25T09:30:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=268207"},"modified":"2025-08-26T15:11:05","modified_gmt":"2025-08-26T13:11:05","slug":"al-via-il-settembre-rendese-ecco-i-primi-due-nomi-della-60esima-edizione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/al-via-il-settembre-rendese-ecco-i-primi-due-nomi-della-60esima-edizione\/","title":{"rendered":"Al via il Settembre Rendese, ecco i primi due nomi della 60esima edizione"},"content":{"rendered":"<p>RENDE \u2013 La <strong>musica italiana<\/strong> protagonista al <strong>Settembre Rendese,<\/strong> il <a href=\"https:\/\/settembrerendese.it\/\" target=\"_blank\" rel=\"noopener\">festival<\/a> giunto alla sua 60esima edizione, che si conferma il pi\u00f9 longevo della Calabria, punto di riferimento culturale e artistico dell\u2019intera regione. Quest&#8217;anno l&#8217;appuntamento \u00e8 <strong>dal 17 al 27 settembre 2025,<\/strong> con una programmazione che si preannuncia ricca e articolata, nel segno della cultura, della musica e della valorizzazione del territorio.<\/p>\n<p>C&#8217;\u00e8 <strong>grande attesa sui nomi degli ospiti<\/strong> della <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/settembre-rendese-dal-17-al-27-settembre-la-60-edizione-dello-storico-festival-di-rende\" target=\"_blank\" rel=\"noopener\"><strong>storica kermesse<\/strong> <\/a>che coinvolge tutta la citt\u00e0 di Rende, dalle contrade al Borgo Antico, fino al cuore pulsante del centro urbano, organizzata dall&#8217;amministrazione comunale, guidata dal sindaco <strong>Sandro Principe<\/strong>, con la <strong>direzione artistica di Alfredo De Luca.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-268315 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Noemi.jpg\" alt=\"\" width=\"358\" height=\"447\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Noemi.jpg 1638w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Noemi-240x300.jpg 240w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Noemi-819x1024.jpg 819w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Noemi-768x960.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Noemi-1229x1536.jpg 1229w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Noemi-336x420.jpg 336w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Noemi-150x188.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Noemi-300x375.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Noemi-696x870.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Noemi-1068x1335.jpg 1068w\" sizes=\"auto, (max-width: 358px) 100vw, 358px\" \/><\/p>\n<h3>Settembre Rendese: arrivano Noemi e i Coma Cose<\/h3>\n<p>In anteprima sveliamo i <strong>primi due nomi<\/strong> degli ospiti del Settembre Rendese. Si canter\u00e0 e si baller\u00e0 con artisti amatissimi del panorama della musica italiana. Ad aprire la kermesse con l\u2019atteso <strong>\u201cconcertone\u201d di Via Rossini,<\/strong> evento che tradizionalmente richiama migliaia di spettatori da tutta la regione, spetter\u00e0 a <strong>Noemi<\/strong>, il <strong>17 settembre alle 21:30 con il Nostalgia Summer Tour<\/strong>.<\/p>\n<p>Nella serata conclusiva, invece, prevista per il <strong>27 settembre,<\/strong> Rende accoglier\u00e0 i <strong>Coma Cose<\/strong>, con un live in programma <strong>in piazza Kennedy nell&#8217;area del Museo del Presente<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-268317 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Coma-Cose-Concerto.jpg\" alt=\"\" width=\"361\" height=\"451\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Coma-Cose-Concerto.jpg 1638w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Coma-Cose-Concerto-240x300.jpg 240w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Coma-Cose-Concerto-819x1024.jpg 819w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Coma-Cose-Concerto-768x960.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Coma-Cose-Concerto-1229x1536.jpg 1229w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Coma-Cose-Concerto-336x420.jpg 336w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Coma-Cose-Concerto-150x188.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Coma-Cose-Concerto-300x375.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Coma-Cose-Concerto-696x870.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Coma-Cose-Concerto-1068x1335.jpg 1068w\" sizes=\"auto, (max-width: 361px) 100vw, 361px\" \/><\/p>\n<p>Due dei protagonisti dell&#8217;ultimo <strong>Festival di Sanremo firmato Carlo Conti<\/strong> arrivano dunque a Rende per l&#8217;atteso festival di fine estate. Noemi sta facendo ballare mezza Italia con la hit in featuring con Rocco Hunt &#8220;Oh Ma&#8221; ed \u00e8 in giro nelle piazza italiane con il <strong>\u201cNostalgia Summer Tour\u201d<\/strong> che far\u00e0 tappa dunque in Calabria per l&#8217;apertura del Settembre Rendese, in attesa dei concerti nei teatri in programma a novembre e del grande evento al Palazzo dello Sport di Roma a dicembre.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-268213\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Primi-nomi-Settembre-Rendese.jpg\" alt=\"Settembre Rendese Noemi e Coma Cose \" width=\"528\" height=\"327\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Primi-nomi-Settembre-Rendese.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Primi-nomi-Settembre-Rendese-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Primi-nomi-Settembre-Rendese-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Primi-nomi-Settembre-Rendese-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Primi-nomi-Settembre-Rendese-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Primi-nomi-Settembre-Rendese-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/08\/Primi-nomi-Settembre-Rendese-356x220.jpg 356w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/><\/p>\n<p>Non da meno i Coma Cose, il duo sul palco e nella vita, composto da California e Fausto Lama che ha da poco presentato il nuovo <strong>album \u2019Vita fusa\u2019,<\/strong> il quinto in studio, per raccontare un nuovo capitolo, molto personale, della loro vita.<\/p>\n<p>Questo solo un piccolo assaggio di quello che sar\u00e0 la 60esima edizione del festival. Nelle prossime ore, infatti, <strong>saranno svelati gli altri artisti<\/strong> che si esibiranno sul palco del Settembre Rendese.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE \u2013 La musica italiana protagonista al Settembre Rendese, il festival giunto alla sua 60esima edizione, che si conferma il pi\u00f9 longevo della Calabria, punto di riferimento culturale e artistico dell\u2019intera regione. Quest&#8217;anno l&#8217;appuntamento \u00e8 dal 17 al 27 settembre 2025, con una programmazione che si preannuncia ricca e articolata, nel segno della cultura, della [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":268210,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[19],"class_list":["post-268207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=268207"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/268210"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=268207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=268207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=268207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}