{"id":26841,"date":"2013-10-23T08:23:51","date_gmt":"2013-10-23T06:23:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=26841"},"modified":"2023-01-17T13:24:22","modified_gmt":"2023-01-17T12:24:22","slug":"11071-anziano-scomparso-a-pedace-avviate-le-ricerche","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11071-anziano-scomparso-a-pedace-avviate-le-ricerche\/","title":{"rendered":"Anziano scomparso a Pedace, avviate le ricerche"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\">APRIGLIANO (CS) &#8211; E\u2019 da luned\u00ec scorso che non si hanno pi\u00f9 notizie di Pietro Palazzo, 89 anni di Pedace.<\/p>\n<p>  <!--more-->  <\/p>\n<p class=\"p1\" style=\"text-align: justify;\">L\u2019uomo con la passione per la caccia era uscito con la sua auto per cercare i suoi cani, smarriti circa venti giorni fa. L\u2019anziano per\u00f2 non \u00e8 pi\u00f9 tornato a casa. Il campo base per le ricerche \u00e8 stato allestito ad Aprigliano nel campo sportivo e sono molti i cittadini che partecipano volontariamente alle ricerche, tra i quali il sindaco di Pedace, Nuccio Martire. Al momento non \u00e8 stata trovata neanche l\u2019auto dell\u2019uomo. <span class=\"s1\">Sul posto per le ricerche ci sono i vigili del fuoco, coadiuvati dall&#8217;Unit\u00e0 cinofila di Vibo Valentia, gli uomini dell&#8217;Arma dei carabinieri, agenti della Guardia di Finanza. Un elicottero aiuter\u00e0 nelle ricerche sorvolando la zona.&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>APRIGLIANO (CS) &#8211; E\u2019 da luned\u00ec scorso che non si hanno pi\u00f9 notizie di Pietro Palazzo, 89 anni di Pedace.<\/p>\n","protected":false},"author":19,"featured_media":26842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-26841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=26841"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/26841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/26842"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=26841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=26841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=26841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}