{"id":268411,"date":"2025-08-27T19:54:48","date_gmt":"2025-08-27T17:54:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=268411"},"modified":"2025-08-27T19:54:55","modified_gmt":"2025-08-27T17:54:55","slug":"piu-donne-nella-scienza-lunical-guida-litalia-con-un-progetto-didattico-sperimentale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/piu-donne-nella-scienza-lunical-guida-litalia-con-un-progetto-didattico-sperimentale\/","title":{"rendered":"Pi\u00f9 donne nella scienza: l&#8217;Unical guida l\u2019Italia con un progetto didattico sperimentale"},"content":{"rendered":"<p>RENDE (CS) &#8211; Promuovere l\u2019accesso delle ragazze e delle giovani donne ai percorsi e alle carriere nelle discipline scientifiche, tecnologiche, ingegneristiche e matematiche, considerate oggi un potente fattore di empowerment femminile. Questo l\u2019obietto del progetto <strong>\u201cSTEM4Teach@Cal: Formazione, innovazione e inclusione nella didattica STEM in Calabria\u201d<\/strong>: un\u2019iniziativa dell\u2019Universit\u00e0 della Calabria che si svilupper\u00e0 nel biennio 2025-2027 e che punta a rafforzare formazione, inclusione e innovazione sociale nel <strong>campo delle discipline STEM, sotto il coordinamento del Dipartimento di Matematica e Informatica<\/strong>. Il progetto avr\u00e0 un forte impatto sul territorio: saranno, infatti, <strong>ben 19 le scuole secondarie di primo e secondo grado della Calabria interessate dalle attivit\u00e0, con circa 800 docenti inseriti in un percorso di formazione specifica e quasi 1000 studenti e studentesse coinvolti<\/strong> nelle sperimentazioni didattiche, con una composizione dei gruppi che sar\u00e0 per almeno il 60% femminile.<\/p>\n<p>Nel primo anno i docenti seguiranno moduli metodologici e tematici anche su diversit\u00e0, equit\u00e0, inclusione e genere, mentre nel secondo anno avranno <strong>il compito di sperimentare in classe i percorsi progettati insieme agli allievi e alle allieve<\/strong>. Parallelamente, saranno attivate attivit\u00e0 di orientamento verso le discipline STEM, in sinergia con le iniziative gi\u00e0 sviluppate dall\u2019ateneo. STEM4Teach@Cal si \u00e8 affermato come progetto di eccellenza a livello nazionale, risultando primo assoluto nella graduatoria del bando \u201cSTEM Universit\u00e0 2024\u201d emanato dal Dipartimento per le Pari Opportunit\u00e0 della Presidenza del Consiglio dei Ministri.<\/p>\n<p><strong>L\u2019Universit\u00e0 della Calabria ha ottenuto il punteggio massimo di 100\/100 e un finanziamento pari a 300 mila euro<\/strong>, che consentir\u00e0 di consolidare un modello formativo innovativo e inclusivo. \u00abQuesto risultato \u2013 commenta il rettore dell\u2019Universit\u00e0 della Calabria, Nicola Leone \u2013 conferma e rafforza l\u2019impegno dell\u2019ateneo sulle pari opportunit\u00e0 e sull\u2019inclusione sociale, per un futuro in cui l\u2019accesso alle carriere scientifiche sia realmente aperto a tutti, senza condizionamenti di genere\u00bb.<\/p>\n<p>Al progetto partecipano anche il <strong>Centro di Women\u2019s Studies \u201cMilly Villa\u201d<\/strong>,<strong> il Digital Education Hub \u2013 DEH ALMA@UniCal, il progetto OrSI<\/strong> (Orientamento Sostenibile e Inclusivo), i<strong> laboratori Agor\u00e0LAB e OpenLAB,<\/strong> oltre a partner esterni come la <strong>Federazione Nazionale Insegnanti (FNISM)<\/strong>, l<strong>\u2019Associazione Italiana per l\u2019Intelligenza Artificiale (AIxIA), il Sila Science Park, il Parco Astronomico \u201cLuigi Lilio\u201d, la rete PRIN ADELANTE e la Fondazione ITS Tirreno Academy.<\/strong> Referenti di ateneo sono Giovanna Vingelli, delegata del Rettore per le Pari Opportunit\u00e0, Annamaria Canino, delegata del Rettore per la formazione insegnanti, e Peppino Sapia, responsabile scientifico del progetto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE (CS) &#8211; Promuovere l\u2019accesso delle ragazze e delle giovani donne ai percorsi e alle carriere nelle discipline scientifiche, tecnologiche, ingegneristiche e matematiche, considerate oggi un potente fattore di empowerment femminile. Questo l\u2019obietto del progetto \u201cSTEM4Teach@Cal: Formazione, innovazione e inclusione nella didattica STEM in Calabria\u201d: un\u2019iniziativa dell\u2019Universit\u00e0 della Calabria che si svilupper\u00e0 nel biennio 2025-2027 [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":268412,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[19],"class_list":["post-268411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=268411"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/268412"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=268411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=268411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=268411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}