{"id":268417,"date":"2025-08-27T16:23:32","date_gmt":"2025-08-27T14:23:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=268417"},"modified":"2025-08-27T16:31:26","modified_gmt":"2025-08-27T14:31:26","slug":"celico-il-consiglio-comunale-approva-la-delibera-per-il-riconoscimento-della-palestina-come-stato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/celico-il-consiglio-comunale-approva-la-delibera-per-il-riconoscimento-della-palestina-come-stato\/","title":{"rendered":"Celico: il Consiglio comunale approva la delibera per il riconoscimento della Palestina come Stato"},"content":{"rendered":"<p>CELICO &#8211; Il <strong>Consiglio comunale di Celico<\/strong> ha approvato una delibera per il <strong>riconoscimento ufficiale dello Stato di Palestina<\/strong>. La proposta, \u00e8 stata presentata nella seduta dell\u2019ultimo Consiglio comunale dal <strong>presidente del Consiglio Mario Scalise<\/strong>, ed \u00e8 stata approvata all\u2019unanimit\u00e0.<\/p>\n<p>\u201cPer noi \u2013 ha affermato il presidente del Consiglio comunale Mario Scalise &#8211; si tratta di un atto doveroso nei confronti del <strong>popolo palestinese<\/strong>, v<strong>ittima di violenze e soprusi in una guerra unilaterale<\/strong> che colpisce soprattutto bambini e civili. L\u2019approvazione di questa mozione \u2013 ha proseguito Scalise &#8211; rappresenta un segnale di <strong>vicinanza e di resistenza<\/strong> all\u2019indifferenza di fronte a tanta sofferenza e ingiustizia\u201d.<\/p>\n<p>Con questo atto,<strong> l\u2019amministrazione comunale di Celico si unisce a tanti altri Comuni italiani che negli ultimi mesi hanno preso posizione su quanto sta accadendo nella striscia di Gaza<\/strong>. \u201cIl nostro auspicio \u2013 ha concluso il presidente del Consiglio comunale di Celico &#8211; \u00e8 che anche il Governo italiano compia riconosca lo Stato di Palestina, interrompendo ogni forma di collaborazione con quella che viene definita \u201cuna tragedia umanitaria\u201d.<\/p>\n<p>L\u2019approvazione della delibera segna <strong>un gesto simbolico ma significativo<\/strong>, volto a rafforzare il dibattito nazionale e internazionale sul riconoscimento della Palestina e sui percorsi possibili per una pace giusta e duratura in Medio Oriente\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CELICO &#8211; Il Consiglio comunale di Celico ha approvato una delibera per il riconoscimento ufficiale dello Stato di Palestina. La proposta, \u00e8 stata presentata nella seduta dell\u2019ultimo Consiglio comunale dal presidente del Consiglio Mario Scalise, ed \u00e8 stata approvata all\u2019unanimit\u00e0. \u201cPer noi \u2013 ha affermato il presidente del Consiglio comunale Mario Scalise &#8211; si tratta [&hellip;]<\/p>\n","protected":false},"author":66,"featured_media":268419,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-268417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=268417"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/268419"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=268417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=268417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=268417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}