{"id":268539,"date":"2025-08-29T09:57:31","date_gmt":"2025-08-29T07:57:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=268539"},"modified":"2025-08-29T09:57:31","modified_gmt":"2025-08-29T07:57:31","slug":"pasquale-tridico-presenta-il-simbolo-della-sua-lista-parla-a-tutti-con-colori-e-simboli-della-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/pasquale-tridico-presenta-il-simbolo-della-sua-lista-parla-a-tutti-con-colori-e-simboli-della-calabria\/","title":{"rendered":"Pasquale Tridico presenta il simbolo della sua lista: \u00abParla a tutti, con colori e simboli della Calabria\u00bb"},"content":{"rendered":"<p>CATANZARO &#8211; Le<strong> elezioni regionali per la Calabria<\/strong> sono sempre pi\u00f9 vicine. <strong>Pasquale Tridico, <\/strong>candidato per il campo largo, brucia tutti gli altri e presenta in maniera ufficiale, sui social, il <strong>simbolo della sua lista<\/strong>. &#8220;Alle elezioni regionali in Calabria oltre ai simboli di tutte le forze politiche del campo progressista che mi sostengono, accanto al mio nome sulla scheda elettorale ci sar\u00e0 come da abitudine anche la lista del Presidente. &#8211; spiega &#8211; Ecco il simbolo: <strong>vuole parlare a tutti, con i colori e le forme della nostra Calabria,<\/strong> del mare e del sole con <strong>l\u2019accento rosso del progresso.<\/strong> Ho deciso di <strong>usare tre parole,<\/strong> parole che raccontano la <strong>fatica<\/strong> e <strong>l\u2019orgoglio<\/strong> di chi resta, la <strong>nostalgia<\/strong> e la <strong>speranza<\/strong> di chi torna, la <strong>tenacia<\/strong> di chi ancora ci crede&#8221; dice l&#8217;ex presidente dell&#8217;Inps.<\/p>\n<p>&#8220;Perch\u00e9 io credo che la Calabria non debba essere soltanto la Terra delle partenze, &#8211; aggiunge &#8211; ma possa <strong>diventare la Terra del ritorno<\/strong>, della dignit\u00e0 e delle possibilit\u00e0. Non possiamo accettare che la nostra terra sia condannata ad essere l\u2019ultima in tutto. Ecco perch\u00e9 <strong>diciamo RESTA:<\/strong> perch\u00e9<strong> chi resta<\/strong> <strong>qui non deve sentirsi un eroe solitario, ma parte di una comunit\u00e0 che lotta&#8221;.<\/strong><\/p>\n<p>&#8220;Diciamo TORNA: perch\u00e9 vogliamo che i nostri figli abbiano finalmente la possibilit\u00e0 di tornare e di costruire il loro futuro qui. &#8211; dice ancora Tridico &#8211; E <strong>diciamo CREDIAMOCI:<\/strong> perch\u00e9 senza crederci, non cambier\u00e0 mai nulla. Voglio incontrare i miei conterranei e voglio sentirmi dire:<strong> \u201cIo resto qui\u201d.<\/strong> E da altri voglio sentirmi dire: <strong>\u201cIo torno\u201d.<\/strong> E da tutti, ma tutti, non mi importa se di destra o di sinistra, da chi magari non vota da tanto tempo perch\u00e8 pensa che tanto non cambier\u00e0 mai niente, da tutti voglio sentire: \u201cCREDIAMOCI\u201d. &#8211; conclude &#8211; Io ci credo e voglio che anche voi ci crediate&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Le elezioni regionali per la Calabria sono sempre pi\u00f9 vicine. Pasquale Tridico, candidato per il campo largo, brucia tutti gli altri e presenta in maniera ufficiale, sui social, il simbolo della sua lista. &#8220;Alle elezioni regionali in Calabria oltre ai simboli di tutte le forze politiche del campo progressista che mi sostengono, accanto [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":268540,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-268539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=268539"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/268540"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=268539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=268539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=268539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}