{"id":268808,"date":"2025-09-05T07:00:03","date_gmt":"2025-09-05T05:00:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=268808"},"modified":"2025-09-02T08:54:48","modified_gmt":"2025-09-02T06:54:48","slug":"stop-alla-barbarie-a-gaza-domani-presidi-della-cgil-anche-in-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/stop-alla-barbarie-a-gaza-domani-presidi-della-cgil-anche-in-calabria\/","title":{"rendered":"&#8220;Stop alla barbarie a Gaza&#8221;, domani presidi della Cgil anche in Calabria"},"content":{"rendered":"<p>COSENZA &#8211; Anche in Calabria la Cgil promuove per domani, sabato 6 settembre presidi in tutti e cinque le citt\u00e0 capoluogo per dire &#8216;no&#8217; alla barbarie in corso a Gaza. L&#8217;organizzazione sindacale invita a partecipare lavoratori e lavoratrici, pensionati e pensionate, studenti e studentesse, il mondo associativo, artisti, intellettuali e giornalisti a unirsi \u2013 contro una delle pi\u00f9 grandi violazioni del diritto umanitario e internazionale.<\/p>\n<p>I presidi calabresi saranno a:<\/p>\n<p>&#8211; <strong>Catanzaro<\/strong>, piazza Prefettura ore 10.30<br \/>\n&#8211; <strong>Vibo Valentia<\/strong>, Corso Vittorio Emanuele ore 10.30<br \/>\n&#8211; <strong>Crotone<\/strong>, piazzale Berlinguer, ore 17<br \/>\n&#8211; <strong>Reggio Calabria<\/strong>, scalinata Teatro Cilea, Corso Garibaldi ore 18<br \/>\n&#8211; <strong>Cosenza<\/strong> (Camere del Lavoro di Cosenza e Pollino Sibaritide Tirreno), piazza XI Settembre ore 17.30<\/p>\n<p>La <strong>Cgil Calabria<\/strong> sostiene la <strong>Global Sumud Flotilla<\/strong>, iniziativa non violenta nata dal basso per <strong>rompere l&#8217;embargo e l&#8217;isolamento della popolazione palestinese <\/strong>e\u00a0ribadisce le richieste avanzate dalla Confederazione sindacale internazionale: interrompere la consegna di armi, raggiungere un cessate il fuoco, garantire l&#8217;ingresso immediato e illimitato degli aiuti umanitari, rilasciare tutti gli ostaggi ei prigionieri politici, riconoscere lo Stato di Palestina, porre fine all&#8217;occupazione, interrompere il commercio con gli insediamenti illegali e rafforzare la democrazia per costruire una pace duratura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Anche in Calabria la Cgil promuove per domani, sabato 6 settembre presidi in tutti e cinque le citt\u00e0 capoluogo per dire &#8216;no&#8217; alla barbarie in corso a Gaza. L&#8217;organizzazione sindacale invita a partecipare lavoratori e lavoratrici, pensionati e pensionate, studenti e studentesse, il mondo associativo, artisti, intellettuali e giornalisti a unirsi \u2013 contro [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":268809,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-268808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=268808"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/268808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/268809"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=268808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=268808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=268808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}