{"id":269558,"date":"2025-09-10T07:18:45","date_gmt":"2025-09-10T05:18:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=269558"},"modified":"2025-09-10T07:18:45","modified_gmt":"2025-09-10T05:18:45","slug":"falerna-sequestrata-discoteca-abusiva-300-persone-in-un-locale-senza-agibilita-ne-sicurezza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/falerna-sequestrata-discoteca-abusiva-300-persone-in-un-locale-senza-agibilita-ne-sicurezza\/","title":{"rendered":"Falerna, sequestrata discoteca abusiva: 300 persone in un locale senza agibilit\u00e0 n\u00e9 sicurezza"},"content":{"rendered":"<p>FALERNA (CZ) \u2013 La guardia di finanza ha scoperto una discoteca abusiva, frequentata da circa <strong>300 persone<\/strong>, priva delle pi\u00f9 elementari misure di sicurezza. Durante una verifica in un locale situato nel Comune di Falerna, le Fiamme Gialle hanno accertato che all\u2019interno era stato organizzato un evento pubblico senza il prescritto certificato di agibilit\u00e0 e senza la SCIA Antincendio, documenti fondamentali per la tutela dell\u2019incolumit\u00e0 degli avventori.<\/p>\n<p>L\u2019accertamento ha rivelato una situazione di <strong>potenziale pericolo per i partecipanti<\/strong>: un <strong>assembramento di centinaia di persone<\/strong> in un ambiente privo delle necessarie autorizzazioni e senza alcuna garanzia di sicurezza in caso di emergenza.\u00a0Alla luce delle gravi violazioni riscontrate, i finanzieri hanno <strong>interrotto immediatamente l&#8217;attivit\u00e0 <\/strong>e\u00a0posto sotto sequestro preventivo i locali e denunciato il responsabile alla Procura della Repubblica di Lamezia Terme. Il sequestro \u00e8 stato poi convalidato dal Giudice per le Indagini Preliminari del Tribunale locale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FALERNA (CZ) \u2013 La guardia di finanza ha scoperto una discoteca abusiva, frequentata da circa 300 persone, priva delle pi\u00f9 elementari misure di sicurezza. Durante una verifica in un locale situato nel Comune di Falerna, le Fiamme Gialle hanno accertato che all\u2019interno era stato organizzato un evento pubblico senza il prescritto certificato di agibilit\u00e0 e [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":188457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-269558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/269558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=269558"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/269558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/188457"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=269558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=269558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=269558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}