{"id":27027,"date":"2013-10-29T08:55:57","date_gmt":"2013-10-29T07:55:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27027"},"modified":"2023-01-17T13:24:32","modified_gmt":"2023-01-17T12:24:32","slug":"11165-barista-di-cellara-scomparso-si-ipotizza-un-omicidio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11165-barista-di-cellara-scomparso-si-ipotizza-un-omicidio\/","title":{"rendered":"Barista di Cellara scomparso, si ipotizza un omicidio"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\">CELLARA (CS) &#8211; &nbsp;E\u2019 scomparso da quasi un mese, Davide Cozza, 48 anni di Cellara, in provincia di Cosenza, gestore di un bar a Piano Lago.<\/p>\n<p>  <!--more-->  <\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Le sue tracce si sono perse la sera del 3 ottobre scorso. Avviate le ricerche da quel giorno, in tutta l\u2019area del Savuto, fino ad oggi non hanno portato a nessun riscontro. Il telefonino dell\u2019uomo risulta irraggiungibile da quella sera, quando sarebbe dovuto rientrare a casa dopo essere stato in campagna. Ma ad oggi Cozza \u00e8 sparito nel nulla e gli inquirenti ipotizzano addirittura che possa essere stato assassinato. L\u2019uomo infatti, secondo familiari e amici, non avrebbe avuto alcun motivo per sparire e dunque non si sarebbe allontanato volontariamente, anche perch\u00e9 l\u2019uomo non avrebbe ne soldi ne documenti. Cozza al momento della scomparsa indossava una polo di colore verde, ha i capelli brizzolati ed \u00e8 alto 1,75 metri. Chiunque avesse sue notizie pu\u00f2 rivolgersi alla stazione dei carabinieri di Mangone (Cs).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CELLARA (CS) &#8211; &nbsp;E\u2019 scomparso da quasi un mese, Davide Cozza, 48 anni di Cellara, in provincia di Cosenza, gestore di un bar a Piano Lago.<\/p>\n","protected":false},"author":19,"featured_media":27028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-27027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27027"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27028"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}