{"id":270361,"date":"2025-09-22T07:00:20","date_gmt":"2025-09-22T05:00:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=270361"},"modified":"2025-09-18T11:22:53","modified_gmt":"2025-09-18T09:22:53","slug":"allunical-torna-la-notte-europea-dei-ricercatori-e-delle-ricercatrici-con-oltre-200-eventi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/allunical-torna-la-notte-europea-dei-ricercatori-e-delle-ricercatrici-con-oltre-200-eventi\/","title":{"rendered":"All&#8217;Unical torna la Notte europea dei ricercatori e delle ricercatrici con oltre 200 eventi"},"content":{"rendered":"<p>RENDE &#8211; Per il dodicesimo anno consecutivo arriva all\u2019Universit\u00e0 della Calabria la <strong>Notte Europea dei Ricercatori e delle Ricercatrici SuperScienceMe. <\/strong>L&#8217;appuntamento \u00e8 per <strong>venerd\u00ec 26 settembre.<\/strong> Un evento unico che coniuga <strong>ricerca e spettacolo<\/strong> promuovendo il <strong>dialogo tra scienza e societ\u00e0.<\/strong><\/p>\n<p>L&#8217;appuntamento di divulgazione scientifica \u2013 che vede l&#8217;Unical capofila insieme all&#8217;Universit\u00e0 Magna Graecia, l&#8217;Universit\u00e0 Mediterranea, l&#8217;Universit\u00e0 della Basilicata, il CNR e la Regione Calabria \u2013 \u00e8 <strong>uno dei nove progetti italiani di Notte europea dei ricercatori e delle ricercatrici<\/strong> <strong>finanziati dalla Commissione europea<\/strong> con l&#8217;obiettivo di creare occasioni di incontro tra ricercatori e cittadini per diffondere la cultura scientifica.<\/p>\n<h3>La mattina all&#8217;Unical con visite, laboratori e spazi di condivisione<\/h3>\n<p>La manifestazione partir\u00e0 <strong>in ateneo alle 8:30,<\/strong> con un ricco catalogo di v<strong>isite prenotabili<\/strong> e tante <strong>nuove iniziative<\/strong>: in piazza Vermicelli sar\u00e0 allestita l\u2019<strong>Agor\u00e0 Pnrr,<\/strong> un\u2019area dedicata alla presentazione dei risultati dei progetti di ricerca Unical finanziati dal PNRR; presso l\u2019Orto botanico lo spazio di <strong>Yoga e Mindfulness Transpersonale <\/strong>offrir\u00e0 la possibilit\u00e0 di \u201cfare amicizia con noi stessi e riscoprire il prezioso contatto con Madre Terra\u201d; novit\u00e0 in programma anche per la sezione \u201cL\u2019Universit\u00e0 dei bambini\u201d, dove oltre ai<strong> laboratori dell\u2019AIRC e a quelli del fumetto,<\/strong> sar\u00e0 possibile partecipare a un <strong>percorso ludico-ginnico<\/strong> con ostacoli da superare per rispondere ai quiz scientifici e a un laboratorio che simula un\u2019attivit\u00e0 di ricerca sociale con metodi creativi e collaborativi sui temi della pace. Tutte le visite possono essere prenotate sul sito di SuperScienceMe.<\/p>\n<h3>Si continua nel pomeriggio a Cosenza lungo Corso Mazzini. La sera il concerto di FRANCO126<\/h3>\n<p>Dopo la mattinata all\u2019Unical dedicata a <strong>esperimenti scientifici, dimostrazioni, giochi, attivit\u00e0 ludico-educative e visite in laboratori, musei, biblioteche e luoghi d\u2019arte,<\/strong> nonch\u00e9 agli spazi dei Dipartimenti e quelli tematici (EU Space, Innovation Space, Gender Space) il pomeriggio, a partire <strong>dalle 16:30<\/strong>, SuperScienceMe si sposter\u00e0, come lo scorso anno, a <strong>Cosenza<\/strong>, lungo <strong>Corso Mazzini,<\/strong> con attivit\u00e0 a cura dei ricercatori Unical, <strong>animazione per bambini, mini tour nel centro storico<\/strong> alla scoperta del patrimonio culturale e urbano e percorsi di Nordic Walking.<\/p>\n<p>Per il gran finale si torna nel campus, a <strong>piazza Vermicelli:<\/strong> in programma alle <strong>21 il concerto gratuito di FRANCO126<\/strong>, preceduto dall\u2019open act del giovane cantautore calabrese Speedy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Per il dodicesimo anno consecutivo arriva all\u2019Universit\u00e0 della Calabria la Notte Europea dei Ricercatori e delle Ricercatrici SuperScienceMe. L&#8217;appuntamento \u00e8 per venerd\u00ec 26 settembre. Un evento unico che coniuga ricerca e spettacolo promuovendo il dialogo tra scienza e societ\u00e0. L&#8217;appuntamento di divulgazione scientifica \u2013 che vede l&#8217;Unical capofila insieme all&#8217;Universit\u00e0 Magna Graecia, l&#8217;Universit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":270363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[19],"class_list":["post-270361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/270361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=270361"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/270361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/270363"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=270361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=270361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=270361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}