{"id":270648,"date":"2025-09-22T12:18:16","date_gmt":"2025-09-22T10:18:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=270648"},"modified":"2025-09-22T12:18:42","modified_gmt":"2025-09-22T10:18:42","slug":"latto-aziendale-dellasp-di-cosenza-che-ridisegna-la-rete-ospedaliera-e-legittimo-e-conforme-alle-norme","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/latto-aziendale-dellasp-di-cosenza-che-ridisegna-la-rete-ospedaliera-e-legittimo-e-conforme-alle-norme\/","title":{"rendered":"L&#8217;atto aziendale dell&#8217;Asp di Cosenza che ridisegna la rete ospedaliera \u00ab\u00e8 legittimo e conforme alle norme\u00bb"},"content":{"rendered":"<p>COSENZA \u2013 L\u2019<strong>Asp di Cosenza<\/strong> interviene per smentire le polemiche sorte negli ultimi giorni attorno all\u2019Atto Aziendale n. <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/annunziata-di-cosenza-ce-il-nuovo-atto-aziendale-ma-i-sindacati-chiedono-interventi-urgenti-e-strutturali\" target=\"_blank\" rel=\"noopener\">2000\/2025<\/a>, finito al centro di critiche e contestazioni. Con una nota ufficiale, la direzione precisa che il documento \u00ab<strong>\u00e8 legittimo e conforme alle disposizioni normative<\/strong>\u00bb, sottolineando la necessit\u00e0 di ristabilire la correttezza dell\u2019informazione e di contrastare \u00ab<strong>ricostruzioni imprecise e fuorvianti<\/strong>\u00bb.<\/p>\n<h3>La rete ospedaliera territoriale e l&#8217;organizzazione<\/h3>\n<p>Con la deliberazione del 19 agosto 2025, l\u2019<strong>Azienda Sanitaria provinciale<\/strong> ha adottato l\u2019A<strong>tto Aziendale n. 2000\/2025<\/strong>, che ridefinisce <strong>assetti organizzativi, funzioni e servizi dei presidi ospedalieri e della sanit\u00e0 territoriale<\/strong>. Il testo \u00e8 stato presentato come una svolta sul piano dell\u2019offerta sanitaria nei territori dell\u2019Alto Tirreno e dell\u2019Alto Jonio. Tuttavia, non mancano le contestazioni su legittimit\u00e0, risorse e tempistiche.<\/p>\n<p>L\u2019Asp chiarisce che l\u2019Atto Aziendale \u00e8 lo strumento previsto dalla legge (art. 3 del D.Lgs. 502\/1992) attraverso cui ogni azienda sanitaria <strong>definisce la propria organizzazione interna<\/strong>, le lin<strong>ee strategiche e le modalit\u00e0 di funzionamento dei servizi<\/strong>. Si tratta, dunque, di un documento adottato dal Direttore Generale nell\u2019esercizio della propria autonomia gestionale, che non ha la funzione di istituire o sopprimere servizi per via legislativa. Il documento, precisa l\u2019Asp, \u00ab<em><strong>stabilisce assetti organizzativi, modelli funzionali e responsabilit\u00e0 interne, nel pieno rispetto delle disposizioni regionali \u2013 in particolare i decreti commissariali DCA n. 54\/2023 e DCA n. 360\/2024 che riguardano la riorganizzazione della rete ospedaliera calabrese<\/strong><\/em>\u00bb.<\/p>\n<h3>Praia e Trebisacce: le precisazioni dell&#8217;Asp di Cosenza<\/h3>\n<p>Uno dei punti al centro del dibattito riguarda <strong>i presidi ospedalieri di Praia a Mare e Trebisacce<\/strong>. L\u2019Atto Aziendale ha previsto in entrambi i casi l<strong>a creazione di due strutture complesse di area chirurgica,<\/strong> ciascuna dotata di 18 posti letto. Una decisione che, secondo la direzione aziendale, rientra pienamente nell\u2019autonomia organizzativa riconosciuta alla stessa Asp.<\/p>\n<p>L\u2019atto cambia lo status dell\u2019ospedale di Trebisacce: da <strong>\u201cOspedale di Zona Disagiata\u201d a Ospedale Generale di Base<\/strong>. Inoltre il &#8220;<strong>Chidichimo<\/strong>&#8221; sar\u00e0 sede di un nuovo D<strong>istretto Sanitario Jonio Nord,<\/strong> dotandosi anche altri servizi diagnostici e specialistica come <strong>Cardiologia, Diabetologia, Ecografia, Gastroenterologia, nonch\u00e9 strutture complesse di Medicina e Chirurgia<\/strong>.<\/p>\n<p>Praia a Mare, nello specifico, \u00e8 al centro del dibattito per via delle funzioni previste che per alcuni superano quanto consentito dalle norme in vigore. Alte critiche evidenziano che l\u2019atto non indica finanziamenti, personale o mezzi tecnologici sufficienti per l\u2019attivazione reale dei reparti. \u00ab<strong><em>Si tratta di un passaggio preliminare<\/em><\/strong> \u2013 si legge nella nota dell&#8217;Asp \u2013 <em>poich\u00e9 i<\/em><strong><em> servizi dovranno successivamente essere autorizzati e finanziati nei modi ordinari\u00bb<\/em><\/strong>.<\/p>\n<h3>&#8220;non introduce deroghe ai decreti commissariali&#8221;<\/h3>\n<p>Nelle ultime settimane non sono mancate interpretazioni discordanti, che hanno messo in dubbio la validit\u00e0 e gli effetti giuridici del documento. L\u2019<a href=\"https:\/\/www.asp.cosenza.it\/\" target=\"_blank\" rel=\"noopener\">Asp<\/a> respinge tali affermazioni, definendole \u00abprive di fondamento\u00bb e riconducibili pi\u00f9 a \u00abun clima politico-elettorale\u00bb che a un\u2019analisi obiettiva degli atti amministrativi. \u00ab<em><strong>Attribuire all\u2019Atto Aziendale effetti che non gli competono<\/strong><\/em>\u2013 ribadisce l\u2019Azienda \u2013<strong> <em>o definirlo privo di validit\u00e0, non corrisponde alla realt\u00e0 dei fatti. L\u2019Atto non introduce deroghe ai decreti commissariali, ma pianifica esclusivamente l\u2019organizzazione interna, cos\u00ec come previsto dalla normativa vigente<\/em><\/strong>\u00bb. La replica dell\u2019Asp di Cosenza cerca di chiudere il caso, ma le polemiche attorno alla sanit\u00e0 territoriale e al futuro dei presidi ospedalieri di Praia a Mare e Trebisacce restano al centro dell\u2019agenda politica e dell\u2019attenzione delle comunit\u00e0 locali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 L\u2019Asp di Cosenza interviene per smentire le polemiche sorte negli ultimi giorni attorno all\u2019Atto Aziendale n. 2000\/2025, finito al centro di critiche e contestazioni. Con una nota ufficiale, la direzione precisa che il documento \u00ab\u00e8 legittimo e conforme alle disposizioni normative\u00bb, sottolineando la necessit\u00e0 di ristabilire la correttezza dell\u2019informazione e di contrastare \u00abricostruzioni [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":270651,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-270648","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/270648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=270648"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/270648\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/270651"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=270648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=270648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=270648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}