{"id":270792,"date":"2025-09-23T14:47:55","date_gmt":"2025-09-23T12:47:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=270792"},"modified":"2025-09-23T14:47:55","modified_gmt":"2025-09-23T12:47:55","slug":"business-meeting-tra-la-camera-di-commercio-di-cosenza-e-quella-di-tirana","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/business-meeting-tra-la-camera-di-commercio-di-cosenza-e-quella-di-tirana\/","title":{"rendered":"Business meeting tra la Camera di Commercio di Cosenza e quella di Tirana"},"content":{"rendered":"<p data-start=\"193\" data-end=\"431\">COSENZA &#8211; Si terr\u00e0 <strong data-start=\"202\" data-end=\"231\">gioved\u00ec 25 settembre 2025<\/strong>, dalle <strong data-start=\"239\" data-end=\"259\">10:30 alle 12:30<\/strong>, presso la sede della Camera di Commercio di Cosenza (Via Calabria 33), il <strong data-start=\"335\" data-end=\"428\">Business Meeting tra la Camera di Commercio di Cosenza e la Camera di Commercio di Tirana<\/strong>.<\/p>\n<p data-start=\"433\" data-end=\"690\">L\u2019iniziativa rappresenta un\u2019importante occasione di dialogo e cooperazione tra le realt\u00e0 economiche di <strong data-start=\"536\" data-end=\"558\">Calabria e Albania<\/strong>, con l\u2019obiettivo di rafforzare i legami istituzionali e creare nuove opportunit\u00e0 di crescita imprenditoriale tra i due territori.<\/p>\n<p data-start=\"692\" data-end=\"870\">La delegazione albanese sar\u00e0 guidata dal presidente della Camera di Commercio di Tirana, <strong data-start=\"781\" data-end=\"797\">Nikolin Jaka<\/strong>, e composta da imprenditori provenienti da diversi settori produttivi.<\/p>\n<p data-start=\"872\" data-end=\"1270\">Nel corso dell\u2019incontro \u00e8 prevista la presentazione ufficiale di un <strong data-start=\"940\" data-end=\"977\">Memorandum of Understanding (MoU)<\/strong>, volto a consolidare le relazioni economiche bilaterali. Particolare attenzione sar\u00e0 dedicata alle <strong data-start=\"1077\" data-end=\"1100\">sessioni one-to-one<\/strong> tra gli imprenditori albanesi e quelli calabresi e arb\u00ebresh\u00eb, pensate per favorire la conoscenza reciproca e gettare le basi di collaborazioni a medio e lungo termine.<\/p>\n<p data-start=\"1272\" data-end=\"1367\">\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Si terr\u00e0 gioved\u00ec 25 settembre 2025, dalle 10:30 alle 12:30, presso la sede della Camera di Commercio di Cosenza (Via Calabria 33), il Business Meeting tra la Camera di Commercio di Cosenza e la Camera di Commercio di Tirana. L\u2019iniziativa rappresenta un\u2019importante occasione di dialogo e cooperazione tra le realt\u00e0 economiche di Calabria [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":175066,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-270792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/270792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=270792"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/270792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/175066"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=270792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=270792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=270792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}