{"id":27088,"date":"2013-10-31T08:18:31","date_gmt":"2013-10-31T07:18:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27088"},"modified":"2023-01-17T13:24:35","modified_gmt":"2023-01-17T12:24:35","slug":"11196-sciopero-settore-turismo-adesioni-anche-dalla-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11196-sciopero-settore-turismo-adesioni-anche-dalla-calabria\/","title":{"rendered":"Sciopero settore Turismo, adesioni anche dalla Calabria"},"content":{"rendered":"<p>COSENZA &#8211; Anche i lavoratori calabresi partecipano allo sciopero del settore del turismo indetto per oggi 31 ottobre da Filcams Cgil, Fisascat Cisl e Uiltucs Uil.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Nella nostra regione si fermano per l\u2019intero turno migliaia di dipendenti di pubblici esercizi, ristoranti, bar, mense aziendali e scolastiche e fast food. Una delegazione di lavoratori calabresi parteciper\u00e0 inoltre alla manifestazione organizzata sempre per oggi a Roma. Sindacati e addetti del settore chiedono la stipula di un contratto nazionale che rispetti il lavoro e i lavoratori. \u201cIn Calabria le ragioni della protesta sono doppie \u2013 afferma <strong>Luigi Scarnati, segretario regionale della Filcams Cgil<\/strong> -. Nel nostro territorio, infatti, mettere in discussione il <strong>contratto nazionale<\/strong> e alcuni istituti contrattuali, ad esempio la tutela delle malattie, ha un impatto fortemente negativo perch\u00e9 va ad aggravare un quadro fatto di lavoro nero e precariato molto diffuso. Bisogna inoltre considerare che in Calabria sono rimasti in attivit\u00e0 pochi grandi gruppi che, oltre ad applicare il contratto collettivo nazionale, stipulano pure dei contratti integrativi di gruppo o aziendali. La tutela dei lavoratori \u00e8 affidata quasi esclusivamente al contratto nazionale che va difeso e migliorato\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>A peggiorare la situazione, la scelta assunta luned\u00ec da Fipe Confcommercio (Federazione italiana pubblici esercizi) di recedere dal Contratto collettivo nazionale, cos\u00ec come gi\u00e0 deciso da Angem (associazione che rappresenta le imprese del settore della ristorazione collettiva). \u201cSi tratta di un atteggiamento incomprensibile se si considera che fino a pochi giorni fa Fipe Confcommercio stava discutendo con i sindacati il rinnovo contrattuale\u201d commenta Scarnati. In Calabria lo sciopero di oggi si intreccia con la vicenda dell\u2019<strong>Autogrill di Tarsia Est<\/strong>. \u201cIl primo giugno scorso con la societ\u00e0 abbiamo firmato un\u2019intesa che prevede la riduzione dell\u2019orario per 11 lavoratori, scongiurando cos\u00ec la mobilit\u00e0 \u2013 spiega Scarnati -. Ad oggi l\u2019accordo viene attuato parzialmente. La Filcams Cgil rivendica al contrario la piena applicazione, per questo abbiamo chiesto un incontro alla Direzione provinciale del lavoro di Cosenza che \u00e8 stato fissato per l\u2019otto novembre\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Anche i lavoratori calabresi partecipano allo sciopero del settore del turismo indetto per oggi 31 ottobre da Filcams Cgil, Fisascat Cisl e Uiltucs Uil.<\/p>\n","protected":false},"author":19,"featured_media":27089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-27088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27088"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27089"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}