{"id":270947,"date":"2025-09-25T09:45:05","date_gmt":"2025-09-25T07:45:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=270947"},"modified":"2025-09-25T10:54:01","modified_gmt":"2025-09-25T08:54:01","slug":"cosenza-strappo-ufficiale-tra-il-ds-fabio-lupo-e-guarascio-e-rottura-definitiva","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-strappo-ufficiale-tra-il-ds-fabio-lupo-e-guarascio-e-rottura-definitiva\/","title":{"rendered":"Cosenza, strappo ufficiale tra il ds Fabio Lupo e Guarascio: \u00e8 rottura definitiva"},"content":{"rendered":"<p>COSENZA &#8211; La notizia era nell&#8217;aria da qualche tempo, adesso c&#8217;\u00e8 anche l&#8217;ufficialit\u00e0: <strong>Fabio Lupo<\/strong> non \u00e8 pi\u00f9 il direttore sportivo del <strong>Cosenza Calcio<\/strong>. La rescissione \u00e8 giunta dopo la vittoria netta contro il Giugliano.<\/p>\n<p>Si pu\u00f2 dire a tutti gli effetti un amore mai sbocciato quello fra il Cosenza guidato dal patron <strong>Eugenio Guarascio<\/strong> e l&#8217;ormai ex direttore sportivo <strong>Fabio Lupo<\/strong>. Da Via Conforti, dopo tante indiscrezioni circolate, \u00e8 arrivato l&#8217;annuncio ufficiale.<\/p>\n<h2>Ds Lupo e il Cosenza, addio dopo pochi mesi<\/h2>\n<p>L&#8217;avventura del direttore Lupo in riva al <strong>Crati<\/strong> \u00e8 durata soltanto poco pi\u00f9 di due mesi. L&#8217;annuncio relativo al suo insediamento era avvenuto lo scorso 11 luglio, ora invece l&#8217;idea di dividere le strade. Il comunicato della societ\u00e0 bruzia parla infatti di una risoluzione consensuale del contratto, con &#8220;effetto immediato&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-264071 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Fabio-Lupo.jpg\" alt=\"Fabio Lupo\" width=\"540\" height=\"338\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Fabio-Lupo.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Fabio-Lupo-300x188.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Fabio-Lupo-768x481.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Fabio-Lupo-671x420.jpg 671w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Fabio-Lupo-150x94.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/07\/Fabio-Lupo-696x436.jpg 696w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/p>\n<p>Da qualche tempo, infatti, <strong>Domenico Roma<\/strong> \u00e8 giunto a Cosenza come <strong>responsabile dell&#8217;area tecnica<\/strong>, ma era chiaro fin da subito che le due figure non avrebbero potuto coesistere. Ora , invece, il divorzio \u00e8 cosa fatta fra il Cosenza e il direttore sportivo Lupo. Un accordo raggiunto dalle parti e la conseguente scelta di separarsi.<\/p>\n<p>La notizia \u00e8 giunta il giorno <strong><a href=\"https:\/\/quicosenza.it\/news\/sport\/il-cosenza-liquida-il-giugliano-con-netto-4-a-1-poker-in-un-marulla-ancora-deserto\" target=\"_blank\" rel=\"noopener\">dopo la vittoria per 4-1 contro il Giugliano<\/a><\/strong>: gi\u00e0 durante il match Lupo non era in tribuna, chiaro segnale di un distacco ormai insanabile. &#8220;A Lupo i ringraziamenti per il lavoro svolto durante il periodo di collaborazione ed i migliori auguri per il prosieguo della sua <strong>carriera<\/strong>&#8220;, si legge nel comunicato ufficiale.<\/p>\n<h3>Quanti sono i ds dell&#8217;era Guarascio<\/h3>\n<p>Eugenio Guarascio \u00e8 giunto a Cosenza nel 2011, da quel momento ha cambiato 10 direttori sportivi (11 se si include Domenico Roma). Si va da <strong>Stefano Fiore<\/strong> (2011-2013) a <strong>Gigi Cond\u00f2<\/strong> (2013-2014), passando per <strong>Mauro Meluso <\/strong>(2014-2016), <strong>Massimo Cerri<\/strong> (2016-gennaio 2017) e <strong>Aladino Valoti<\/strong> (gennaio 2017-giugno 2017).<\/p>\n<p>Ma l&#8217;elenco non finisce qui perch\u00e9 a Cosenza sono giunti: <strong>Stefano Trinchera<\/strong> (giugno 2017-giugno 2021), <strong>Roberto Goretti<\/strong> (luglio 2021-giugno 2022) e <strong>Roberto Gemmi<\/strong> (giugno 2022-giugno 2024). Gli ultimi due sono invece <strong>Gennaro Delvecchio<\/strong> (giugno 2024-luglio 2025) e <strong>Fabio Lupo<\/strong> (luglio 2025-settembre 2025).<\/p>\n<h3>La mobilitazione dei tifosi<\/h3>\n<p>Ancora una volta il <strong>tifo organizzato<\/strong> ha scelto di rimanere fuori dallo stadio &#8220;San Vito-Gigi Marulla&#8221; prima della gara contro il Giugliano. Adesso si chiama a raccolta il pubblico di fede rossobl\u00f9: &#8220;\u00e8 il momento di far sentire la nostra voce&#8221;, si legge sulla locandina condivisa anche dai gruppi ultras cosentini. L&#8217;evento \u00e8 in programma <strong>luned\u00ec 29 settembre<\/strong> 2025 alle <strong>ore 18<\/strong> presso il <strong>Cinema San Nicola <\/strong>(<strong>Via Rivocati<\/strong>).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-270961 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/Assemblea-pubblica-Cosenza-Calcio.jpg\" alt=\"\" width=\"540\" height=\"675\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/Assemblea-pubblica-Cosenza-Calcio.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/Assemblea-pubblica-Cosenza-Calcio-240x300.jpg 240w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/Assemblea-pubblica-Cosenza-Calcio-819x1024.jpg 819w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/Assemblea-pubblica-Cosenza-Calcio-768x960.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/Assemblea-pubblica-Cosenza-Calcio-336x420.jpg 336w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/Assemblea-pubblica-Cosenza-Calcio-150x188.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/Assemblea-pubblica-Cosenza-Calcio-300x375.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/Assemblea-pubblica-Cosenza-Calcio-696x870.jpg 696w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La notizia era nell&#8217;aria da qualche tempo, adesso c&#8217;\u00e8 anche l&#8217;ufficialit\u00e0: Fabio Lupo non \u00e8 pi\u00f9 il direttore sportivo del Cosenza Calcio. La rescissione \u00e8 giunta dopo la vittoria netta contro il Giugliano. Si pu\u00f2 dire a tutti gli effetti un amore mai sbocciato quello fra il Cosenza guidato dal patron Eugenio Guarascio [&hellip;]<\/p>\n","protected":false},"author":93,"featured_media":265762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-270947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/270947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=270947"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/270947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/265762"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=270947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=270947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=270947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}