{"id":271002,"date":"2025-09-25T16:04:08","date_gmt":"2025-09-25T14:04:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=271002"},"modified":"2025-09-25T16:04:08","modified_gmt":"2025-09-25T14:04:08","slug":"alberi-di-quercia-tagliati-e-rubati-due-arresti-sequestrati-85-quintali-di-legname","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/alberi-di-quercia-tagliati-e-rubati-due-arresti-sequestrati-85-quintali-di-legname\/","title":{"rendered":"Alberi di quercia tagliati e rubati: due arresti. Sequestrati 85 quintali di legname"},"content":{"rendered":"<p>COTRONEI (KR) &#8211; Alberi di quercia tagliati, rubati e trasportati su un furgone. Nei giorni scorsi i militari del Nucleo Carabinieri \u201cParco\u201d di Cotronei, insieme ai militari di Petilia Policastro e Santa Severina, hanno tratto in arresto in flagranza di reato, <strong>due persone.<\/strong><\/p>\n<p>I carabinieri li hanno sorpresi in localit\u00e0 \u201c<strong>Chianette \u2013 Macchia della Castagna\u201d<\/strong> nel Comune di Cotronei, all\u2019interno della Zona di Protezione Speciale denominata \u201c<strong>Marchesato Fiume Neto<\/strong>\u201d limitrofa al parco Nazionale della <a href=\"https:\/\/quicosenza.it\/news\/calabria\/taglio-illegale-di-alberi-nel-parco-della-sila-scoperti-e-denunciati-i-predatori-di-legname\">Sila<\/a>. I militari hanno accertato che in terreni demaniali di propriet\u00e0 del Comune di Cotronei, erano stati abbattuti e trafugati 69 alberi di alto fusto di essenze quercine.<\/p>\n<h3>Sul furgone 25 quintali di alberi rubati<\/h3>\n<p>I due soggetti sono stati fermati a bordo di un automezzo carico di<strong> 25 quintali<\/strong> di legname appena sottratto dal demanio comunale. Le successive perquisizioni domiciliari hanno permesso di rinvenire e sequestrare ulteriori <strong>60 quintali di legname.<\/strong> Sotto sequestro anche la strumentazione utilizzata per l\u2019abbattimento e il depezzamento del materiale boschivo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-271004 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/furto-legna-cotronei-parco-sila-02.jpg\" alt=\"\" width=\"586\" height=\"362\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/furto-legna-cotronei-parco-sila-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/furto-legna-cotronei-parco-sila-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/furto-legna-cotronei-parco-sila-02-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/furto-legna-cotronei-parco-sila-02-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/furto-legna-cotronei-parco-sila-02-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/furto-legna-cotronei-parco-sila-02-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/09\/furto-legna-cotronei-parco-sila-02-356x220.jpg 356w\" sizes=\"auto, (max-width: 586px) 100vw, 586px\" \/><\/p>\n<p>L\u2019area <a href=\"https:\/\/www.parks.it\/IT9320302\/map.php\" rel=\"noopener\">ZPS<\/a> \u201cMarchesato Fiume Neto\u201d \u00e8 tutelata ai sensi della direttiva uccelli (2009\/147\/CE). Rappresenta uno dei pi\u00f9 importanti ecosistemi avifaunistici, di fondamentale importanza per la nidificazione, il transito migratorio e il riparo di numerose specie. Tra queste il <strong>Biancone<\/strong> (Circaetus gallicus) e <strong>l\u2019Aquila reale<\/strong> (Aquila chrysaetos).<\/p>\n<p>Il Pubblico Ministero di turno ha disposto per entrambi la <strong>misura degli arresti domiciliari<\/strong> presso le rispettive abitazioni. Elevate sanzioni amministrative per un importo superiore ai 4mila euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COTRONEI (KR) &#8211; Alberi di quercia tagliati, rubati e trasportati su un furgone. Nei giorni scorsi i militari del Nucleo Carabinieri \u201cParco\u201d di Cotronei, insieme ai militari di Petilia Policastro e Santa Severina, hanno tratto in arresto in flagranza di reato, due persone. I carabinieri li hanno sorpresi in localit\u00e0 \u201cChianette \u2013 Macchia della Castagna\u201d [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":271003,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-271002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/271002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=271002"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/271002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/271003"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=271002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=271002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=271002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}