{"id":27126,"date":"2013-11-01T07:46:28","date_gmt":"2013-11-01T06:46:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=27126"},"modified":"2023-01-17T13:24:37","modified_gmt":"2023-01-17T12:24:37","slug":"11215-sequestrati-pezzi-di-una-chiesa-smontata-a-montegiordano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11215-sequestrati-pezzi-di-una-chiesa-smontata-a-montegiordano\/","title":{"rendered":"Sequestrati pezzi di una Chiesa &#8220;smontata&#8221; a Montegiordano"},"content":{"rendered":"<p>GIOIA TAURO (RC) &#8211; Sequestrati nel porto di Gioia Tauro 11 container, con le parti murarie della chiesa della Madonna del Carmine di Montergiodano in provincia di Cosenza.<\/p>\n<p>  <!--more-->  <\/p>\n<p>L&#8217;operazione \u00e8 stata compiuta dai carabinieri del Nucleo tutela patrimonio culturale di Cosenza, con i militari di Corigliano calabro e l&#8217;ufficio delle dogane. I container erano in partenza verso gli Stati Uniti per l&#8217;installazione dell&#8217;artista Francesco Vezzoli nel cortile del Moma di New York. L\u2019artista, aveva smontato pezzo per pezzo la chiesa sconsacrata per trasferire tutto a New York, ma la sua iniziativa non \u00e8 piaciuta ai cittadini di Montegiordano che hanno chiesto l\u2019intervento della della Soprintendenza di Cosenza. Il provvedimento \u00e8 stato emesso dalla Procura della Repubblica di Palmi. L&#8217;operazione si \u00e8 resa necessaria per evitare che la struttura smontata della chiesa, di interesse storico, artistico e monumentale, partisse verso gli Stati Uniti. I carabinieri hanno anche sequestrato i resti dell&#8217;antica cappella gentilizia nonch\u00e8 altri 14 conci in muratura gi\u00e0 imballati insieme ad altri blocchi murari, sempre riconducibili alla Chiesa del Carmine. Il reato ipotizzato e&#8217; tentata esportazione illecita di beni culturali. I pezzi della Chiesa sconsacrata di Montegiordano sarebbero serviti ad arricchire il progetto Trinity, a cui l&#8217;artista sta lavorando &#8211; oltre che per il Moma ps1 &#8211; anche per il Moca di Los Angeles e il Maxxi di Roma. Secondo le indagini qualche mese fa, l&#8217;artista Vezzoli, considerato che la chiesa si trova su un terreno privato, aveva contattato il proprietario ed acquistato la struttura attraverso Internet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GIOIA TAURO (RC) &#8211; Sequestrati nel porto di Gioia Tauro 11 container, con le parti murarie della chiesa della Madonna del Carmine di Montergiodano in provincia di Cosenza.<\/p>\n","protected":false},"author":19,"featured_media":27127,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-27126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=27126"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/27126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/27127"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=27126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=27126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=27126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}